{"id":97,"date":"2014-03-05T08:46:35","date_gmt":"2014-03-05T08:46:35","guid":{"rendered":"http:\/\/www.erekibeon.com\/trastero\/?p=97"},"modified":"2015-01-10T16:33:25","modified_gmt":"2015-01-10T15:33:25","slug":"edicto-sobre-precios-maximos-en-la-roma-de-diocleciano","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/edicto-sobre-precios-maximos-en-la-roma-de-diocleciano\/","title":{"rendered":"Edicto sobre precios m\u00e1ximos en la Roma de Diocleciano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/3.bp.blogspot.com\/_lTY0Lp9h6Qc\/S-Bxq1qJ-jI\/AAAAAAAAR5M\/2O-e4vM7p5g\/s400\/mercader.jpg\" alt=\"\" width=\"320\" height=\"257\" \/>V\u00eda <a href=\"https:\/\/plus.google.com\/u\/0\/+Ram\u00f3nDomingo\/posts\/acCV67qLcXj\" target=\"_blank\">este post de google Plus<\/a>,<strong>\u00a0<a href=\"https:\/\/plus.google.com\/u\/0\/115639861585278675340\/posts\" target=\"_blank\">El Poderoso Crom<\/a> <\/strong>pone a disposici\u00f3n de todo el mundo <a href=\"https:\/\/f214aed7-a-62cb3a1a-s-sites.googlegroups.com\/site\/adduartes\/home\/Edicto.pdf?attachauth=ANoY7coh5autaIKCPX1dB6FvMTTSIdMTGr5_Tz0zryabmJZ_03YOzMaxwA_SHc1Rq4M_GrtAKc1yU0ov6FoZMk-3yG0SSS6uGZGvvfG-4x-h3Sqrw9AdKPOYGaRholVSruLq7ZrpbA6sDF2WJQ7MtC2B6ORdwLcwLnFuzyZlHeHOQPumeCBDFQ5SXC0kGIYgFpa8Fmj6Np67EdU6HIljk04jrr_JFakQ1A%3D%3D&amp;attredirects=0\" target=\"_blank\">este pdf con una lista de precios <\/a>de lo m\u00e1s completa. Ideal para cualquier partida en la antigua Roma y una gu\u00eda estupenda para partidas en el mundo antiguo en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00eda este post de google Plus,\u00a0El Poderoso Crom pone a disposici\u00f3n de todo el mundo este pdf con una lista de precios de lo m\u00e1s completa. Ideal para cualquier partida en la antigua Roma y una gu\u00eda estupenda para partidas en el mundo antiguo en general.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,8,13,369],"tags":[496,479,495],"class_list":["post-97","post","type-post","status-publish","format-standard","hentry","category-historia","category-cosas-de-internet","category-otros-blogs","category-trastero","tag-antigua-roma","tag-pdf","tag-precios"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":15051,"url":"https:\/\/www.erekibeon.com\/blog\/visigodos\/","url_meta":{"origin":97,"position":0},"title":"Visigodos","author":"Erek\u00edbeon","date":"15\/09\/2019","format":false,"excerpt":"Si hace unas semanas me hubi\u00e9rais preguntado por los Visigodos, mi primera reacci\u00f3n hubiera sido tal que \u00e9sta: y posiblemente os hubiera respondido lo t\u00edpico: lo de los suevos, los v\u00e1ndalos y los alanos, lo de la lista de los reyes godos, lo de que estuvieron unos 200 a\u00f1os hasta\u2026","rel":"","context":"En \u00abHistoria\u00bb","block_context":{"text":"Historia","link":"https:\/\/www.erekibeon.com\/blog\/category\/historia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/visigodoscatalaunia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/visigodoscatalaunia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/visigodoscatalaunia.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/visigodoscatalaunia.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/visigodoscatalaunia.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/visigodoscatalaunia.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1111,"url":"https:\/\/www.erekibeon.com\/blog\/aluvion-de-noticias-y-novedades-el-mundillo-se-mueve\/","url_meta":{"origin":97,"position":1},"title":"Aluvi\u00f3n de noticias y novedades. El mundillo se mueve.","author":"Erek\u00edbeon","date":"04\/05\/2010","format":false,"excerpt":"Ejem. Est\u00e1 llegando un momento en el que, al igual que el buen Cruz de Caminos, estoy temiendo que este blog se convierta en un mero tabl\u00f3n de noticias. Esto no s\u00f3lo me sirve como tir\u00f3n de orejas porque estoy vagueando cosa mala en el blog, sino que tambi\u00e9n significa\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/2.bp.blogspot.com\/_CbQVPSTbe3w\/S3aGk2SeVDI\/AAAAAAAALsE\/I7JdGAtDho4\/S1600-R\/logomarcadeleste.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1211,"url":"https:\/\/www.erekibeon.com\/blog\/novedades-retroclonicas\/","url_meta":{"origin":97,"position":2},"title":"Novedades retrocl\u00f3nicas","author":"Erek\u00edbeon","date":"02\/06\/2010","format":false,"excerpt":"Pues la semana est\u00e1 siendo muy interesante para el movimiento de la Vieja Escuela, con tres novedades rese\u00f1ables... \u00a1y dos de ellas en castellano! Vamos all\u00e1. Dark Dungeons \u00bfFalta ya alguna versi\u00f3n de D&D por \"retroclonar\" en ingl\u00e9s? \u00a0Ten\u00edamos retroclones de OD&D, de la versi\u00f3n de Moldvay, de la versi\u00f3n\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/rollplay.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/rollplay.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/rollplay.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/rollplay.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12001,"url":"https:\/\/www.erekibeon.com\/blog\/semper-initiativus-unum-od-d-setting-posts-in-pdf\/","url_meta":{"origin":97,"position":3},"title":"Semper Initiativus Unum: OD&#038;D Setting Posts in PDF","author":"Erek\u00edbeon","date":"21\/06\/2013","format":"link","excerpt":"Semper Initiativus Unum: OD&D Setting Posts in PDF\u00bfC\u00f3mo era el setting original del OD&D? Pues bien, en este blog se han currado unos art\u00edculos extrapol\u00e1ndolo a partir de las tablas de encuentros que vienen en el primer D&D. Y el resultado es un mundo bastante extra\u00f1o, donde es muy habitual\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":14725,"url":"https:\/\/www.erekibeon.com\/blog\/completando-colecciones\/","url_meta":{"origin":97,"position":4},"title":"Completando colecciones","author":"Erek\u00edbeon","date":"09\/11\/2018","format":false,"excerpt":"No lo niego, hay veces que me entra alg\u00fan remordimiento cuando contemplo tantos juegos en las estanter\u00edas de mi casa. A fin de cuentas, fueron creados para ser jugados... y no creo que lo haya hecho ni con la d\u00e9cima parte de los que tengo. Luego pienso en los que\u2026","rel":"","context":"En \u00abLibros\u00bb","block_context":{"text":"Libros","link":"https:\/\/www.erekibeon.com\/blog\/category\/libros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/11\/enemigointeriorcomplete.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/11\/enemigointeriorcomplete.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/11\/enemigointeriorcomplete.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/11\/enemigointeriorcomplete.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4097,"url":"https:\/\/www.erekibeon.com\/blog\/risus-en-una-pagina-y-en-castellano\/","url_meta":{"origin":97,"position":5},"title":"Risus en una p\u00e1gina&#8230; y en castellano","author":"Erek\u00edbeon","date":"08\/06\/2012","format":false,"excerpt":"Hace unos meses os comentaba que S. John Ross hab\u00eda sacado una edici\u00f3n de bolsillo\u00a0de su juego, consiguiendo la proeza de constre\u00f1ir ese tocho combaestanter\u00edas de 6 p\u00e1ginas \u00a1en un solo folio!. Pues bien, despu\u00e9s de realizar una nueva traducci\u00f3n partiendo de la que hizo Jokin Gonz\u00e1lez\u00a0(adaptando, recortando y subsanando\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2012\/06\/risus-e1470039814410.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}