{"id":6222,"date":"2014-05-31T00:52:58","date_gmt":"2014-05-30T22:52:58","guid":{"rendered":"http:\/\/www.erekibeon.com\/blog\/?p=6222"},"modified":"2026-04-26T18:24:17","modified_gmt":"2026-04-26T16:24:17","slug":"ya-llego","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/ya-llego\/","title":{"rendered":"Ya lleg\u00f3"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">As\u00ed es, el pasado jueves, d\u00eda 29 de mayo, vino&nbsp;por fin el&nbsp;Peque\u00f1o B\u00e1rbaro al mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ha sido un parto m\u00e1s complicado que el de su hermana, lo que ha hecho los \u00faltimos d\u00edas un poco durillos, pero desde entonces&nbsp;s\u00f3lo hay buenas noticias. La mam\u00e1 est\u00e1 recuper\u00e1ndose muy bien y \u00e9l est\u00e1 con un ciclo de&nbsp;antibi\u00f3tico,&nbsp;pero por lo dem\u00e1s&nbsp;est\u00e1 estupendamente. De hecho, no he podido evitar sentirme orgulloso cuando el Peque\u00f1o B\u00e1rbaro se revolvi\u00f3 el primer d\u00eda de tal forma que la enfermera&nbsp;tuvo&nbsp;que llamar a otra para que le ayudase a controlarlo. \u00a1\u00c9l solo contra dos enfermeras! El tiarr\u00f3n ya va apuntando maneras, ya XDDD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En fin, que empieza para nuestra familia una nueva etapa llena de cambios.&nbsp;Y uno de los primeros que hay que&nbsp;hacer es&#8230; la cabecera del blog, claro \ud83d\ude1b<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.erekibeon.com\/blog\/ano-nuevo-cabecera-nueva\/\">Como recordar\u00e9is<\/a>, en enero de este a\u00f1o el&nbsp;inconfundible&nbsp;<strong><a href=\"https:\/\/manusaez.blogspot.com.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">Manu Saez<\/a><\/strong>&nbsp;le dio su toque a los personajes creados por <strong><a href=\"https:\/\/dibujariointeligente.blogspot.com.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dibujario <\/a><\/strong>para anunciar lo que se nos ven\u00eda encima:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/01\/cabecerapmyf-2.3.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"300\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/01\/cabecerapmyf-2.3.gif\" alt=\"cabecerapmyf-2.3\" class=\"wp-image-5972\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pues bien, cuando supimos que lo que ven\u00eda era un chaval,&nbsp;tuve la suerte de poder contar con la mism\u00edsima<strong> <a href=\"https:\/\/eldesvanderu-mor.blogspot.com.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">RU-MOR<\/a>, <\/strong>\u00faltimamente ocupada con las ilustraciones de <a href=\"https:\/\/www.walkure.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">Walk\u00fcre<\/a>, para que hiciera&nbsp;su propia&nbsp;versi\u00f3n:<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/03\/cabecerapmyf-con-ilustraci\u00f3n-\u00aaRU-MOR.gif\"><img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"300\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/03\/cabecerapmyf-con-ilustraci\u00f3n-\u00aaRU-MOR.gif\" alt=\"cabecerapmyf con ilustraci\u00f3n \u00aaRU-MOR\" class=\"wp-image-6141\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y yo&nbsp;sigo sin salir de mi asombro. \u00c9ste es el resultado final tras un&nbsp;par de&nbsp;mails, y con tan s\u00f3lo una precisi\u00f3n sobre las naricillas&nbsp;\ud83d\ude1b No tengo ni idea de c\u00f3mo ha logrado plasmar exactamente lo que ten\u00eda en la cabeza,&nbsp;pero mi Reina y mi Princesa aplaudieron a rabiar cuando la vieron por primera vez&#8230; y encima me ha ense\u00f1ado bastantes cosillas sobre formatos de imagen e impresiones, jejeje. \u00a1Much\u00edsimas gracias desde aqu\u00ed, dama RU-MOR!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero claro, con esta cabecera tan genial no he tenido m\u00e1s remedio que liarme la manta a la cabeza y darle un peque\u00f1o cambio&nbsp;tambi\u00e9n la plantilla del blog. Al final he escogido el tema <a href=\"https:\/\/wordpress.org\/themes\/tempera\" target=\"_blank\" rel=\"noopener noreferrer\">Tempera<\/a> para sustituir al <a href=\"https:\/\/wordpress.org\/themes\/graphene\" target=\"_blank\" rel=\"noopener noreferrer\">Graphene<\/a> que ten\u00eda hasta ahora, sobre todo por&nbsp;su&nbsp;dise\u00f1o adaptativo y&nbsp;por la forma de presentar&nbsp;las im\u00e1genes de los posts,&nbsp;que&nbsp;le da un aire mucho m\u00e1s&nbsp;estiloso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y poco m\u00e1s. Intentar\u00e9 no retrasarme tanto como hasta ahora en actualizar el blog&#8230; aunque espero que entend\u00e1is el motivo, jejeje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2019\/02\/20140531-As\u00ed-es-el-pasado-jueves-d\u00eda-29-de-may.html\" target=\"_blank\" rel=\"noopener noreferrer\">&nbsp;Comentarios en Google Plus<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed es, el pasado jueves, d\u00eda 29 de mayo, vino&nbsp;por fin el&nbsp;Peque\u00f1o B\u00e1rbaro al mundo. Ha sido un parto m\u00e1s complicado que el de su hermana, lo que ha hecho los \u00faltimos d\u00edas un poco durillos, pero desde entonces&nbsp;s\u00f3lo hay buenas noticias. La mam\u00e1 est\u00e1 recuper\u00e1ndose muy bien y \u00e9l est\u00e1 con un ciclo de&nbsp;antibi\u00f3tico,&nbsp;pero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12],"tags":[253,79],"class_list":["post-6222","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-cabecera","tag-ninos-2"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":14081,"url":"https:\/\/www.erekibeon.com\/blog\/estrenando-cabecera\/","url_meta":{"origin":6222,"position":0},"title":"Estrenando cabecera","author":"Erek\u00edbeon","date":"20\/10\/2017","format":false,"excerpt":"Y es que el Peque\u00f1o B\u00e1rbaro ya hace una temporada que no lleva ni pa\u00f1ales ni chupete, as\u00ed que iba siendo hora de darle un retoque a las figurillas que nos representan al lado del t\u00edtulo. Para esta ocasi\u00f3n he tenido el inmenso honor y el placer de contar con\u2026","rel":"","context":"En \u00abFrikismo\u00bb","block_context":{"text":"Frikismo","link":"https:\/\/www.erekibeon.com\/blog\/category\/frikismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":5956,"url":"https:\/\/www.erekibeon.com\/blog\/ano-nuevo-cabecera-nueva\/","url_meta":{"origin":6222,"position":1},"title":"A\u00f1o nuevo, cabecera nueva","author":"Erek\u00edbeon","date":"01\/01\/2014","format":false,"excerpt":"Desde que\u00a0Dibujario\u00a0me hiciera en 2012\u00a0la nueva cabecera, con esas caricaturas tan simp\u00e1ticas, sab\u00eda que acabar\u00eda haciendo algo m\u00e1s con ellas. Entre unas cosas y otras lo fui dejando... hasta que ha sucedido lo \u00fanico que hac\u00eda inevitable cambiarlas. \u00bfOs imagin\u00e1is lo que es? Efectivamente, para finales de Junio \u00a1seremos cuatro\u2026","rel":"","context":"En \u00abVida cotidiana\u00bb","block_context":{"text":"Vida cotidiana","link":"https:\/\/www.erekibeon.com\/blog\/category\/vida-cotidiana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/01\/cabecerapmyf-2.2.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/01\/cabecerapmyf-2.2.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/01\/cabecerapmyf-2.2.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2014\/01\/cabecerapmyf-2.2.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4360,"url":"https:\/\/www.erekibeon.com\/blog\/nueva-cabecera-e-inauguracion-de-la-biblioteca\/","url_meta":{"origin":6222,"position":2},"title":"Nueva cabecera e inauguraci\u00f3n de la Biblioteca","author":"Erek\u00edbeon","date":"14\/09\/2012","format":false,"excerpt":"Seguro que no os habr\u00e9is dado cuenta porque la mayor\u00eda me le\u00e9is por lectores RSS o cosas as\u00ed, pero me llena de orgullo y satisfacci\u00f3n haceros notar que... \u00a1estreno cabecera! Y mira que yo soy poco de hacer cambios, y menos a\u00fan est\u00e9ticos. Yo puedo estarme perfectamente toda la vida\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/www.erekibeon.com\/blog\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/camiseta1fail.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/camiseta1fail.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/camiseta1fail.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/camiseta1fail.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6037,"url":"https:\/\/www.erekibeon.com\/blog\/y-sera-un-pequeno-barbaro\/","url_meta":{"origin":6222,"position":3},"title":"&#8230; y ser\u00e1 un peque\u00f1o b\u00e1rbaro","author":"Erek\u00edbeon","date":"10\/02\/2014","format":false,"excerpt":"Efectivamente. A pesar de los antecedentes familiares (pr\u00e1cticamente todo nuestro entorno familiar tiene descendencia de un solo sexo),\u00a0\u00a1ser\u00e1 un ni\u00f1o!\u00a0Y lo m\u00e1s importante, parece que viene perfectamente. Aunque yo ya estaba mentalmente dispuesto para otra ni\u00f1a, no voy a negar que me hace mucha ilusi\u00f3n que sea un chaval. Para\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/5237301530_5ac8071245_zpsee11ee8c.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1031,"url":"https:\/\/www.erekibeon.com\/blog\/the-ragworld\/","url_meta":{"origin":6222,"position":4},"title":"The Ragworld","author":"Erek\u00edbeon","date":"17\/03\/2010","format":false,"excerpt":"Por si fueran pocos los jaleos roleros en los que estoy metido \u00faltimamente, con los apuros de tiempo que por s\u00ed solo generan, encima tambi\u00e9n estoy en un proyecto con otros dos compa\u00f1eros de curro para hacer una especie de serie para la web. No se trata de nada profesional,\u2026","rel":"","context":"En \u00abInternet\u00bb","block_context":{"text":"Internet","link":"https:\/\/www.erekibeon.com\/blog\/category\/cosas-de-internet\/"},"img":{"alt_text":"Cabecera Ragworld","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2010\/03\/ragworld.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6239,"url":"https:\/\/www.erekibeon.com\/blog\/jugar-un-apocalipsis-zombi-con-dd-3-x-y-similares\/","url_meta":{"origin":6222,"position":5},"title":"Jugar un Apocalipsis Zombi con D&#038;D 3.x, Pathfinder y similares","author":"Erek\u00edbeon","date":"15\/09\/2014","format":false,"excerpt":"Seguramente esta entrada habr\u00eda estado de actualidad all\u00e1 por abril, antes de saliera\u00a0el PDF gratuito de D&D 5\u00aa, con todas las\u00a0movidas que han acompa\u00f1ado esta nueva edici\u00f3n (el culebr\u00f3n de los colaboradores yankis\u00a0y\u00a0la no traducci\u00f3n al castellano), el mecenazgo de Ablaneda, la llegada por fin del Spirit of the Century\u2026","rel":"","context":"En \u00abMedieval\u00bb","block_context":{"text":"Medieval","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/medieval\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Zombie_attack_by_GuzBoroda_zps452f1048.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Zombie_attack_by_GuzBoroda_zps452f1048.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Zombie_attack_by_GuzBoroda_zps452f1048.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Zombie_attack_by_GuzBoroda_zps452f1048.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/6222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=6222"}],"version-history":[{"count":1,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/6222\/revisions"}],"predecessor-version":[{"id":26729,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/6222\/revisions\/26729"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=6222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=6222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=6222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}