{"id":476,"date":"2009-03-31T22:05:41","date_gmt":"2009-03-31T21:05:41","guid":{"rendered":"http:\/\/erekibeon.com\/?p=476"},"modified":"2022-12-10T20:39:52","modified_gmt":"2022-12-10T19:39:52","slug":"quedandome-sin-excusas","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/quedandome-sin-excusas\/","title":{"rendered":"Qued\u00e1ndome sin excusas"},"content":{"rendered":"<p>Uno de los proyectos que tengo por ah\u00ed pululando en mi mente (y en el google docs) es el de crear un peque\u00f1o \u00abcaj\u00f3n de arena\u00bb al estilo de las <a href=\"https:\/\/arsludi.lamemage.com\/index.php\/78\/grand-experiments-west-marches\/\" target=\"_blank\" rel=\"noopener noreferrer\">West Marches<\/a> de Ben Robbins o los <a href=\"https:\/\/web.archive.org\/web\/20160404211740\/https:\/\/www.goodman-games.com:80\/4380preview.html\" target=\"_blank\" rel=\"noopener noreferrer\">Points of Light<\/a> de Robert Conley y Dwayne Gillingham. Tengo los art\u00edculos, tengo las <a href=\"https:\/\/erekibeon.com\/blog\/todo-al-azar\/\" target=\"_blank\" rel=\"noopener noreferrer\">tablas<\/a>, tengo el<a href=\"https:\/\/www.enworld.org\/threads\/looking-for-the-aks-hex-mapper.241913\/\" target=\"_blank\" rel=\"noopener noreferrer\"> mapeador<\/a>&#8230; pero nunca me decido a sentarme a poner por escrito todo lo que tengo que preparar, o a dibujar el mapa. Prefiero hacer otras cosas como escribir aqu\u00ed, por ejemplo.<\/p>\n<p>Uno de los \u00abperos\u00bb que sol\u00eda ponerme es que el mapa que sale con el AKS es demasiado b\u00e1sico y que queda fatal. Pero despu\u00e9s de ver esto&#8230;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/3.bp.blogspot.com\/_CbQVPSTbe3w\/ScZ8DPiuYXI\/AAAAAAAAIw4\/Wp61GVzBJUM\/s1600\/IMG_3234.JPG\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full\" src=\"https:\/\/3.bp.blogspot.com\/_CbQVPSTbe3w\/ScZ8DPiuYXI\/AAAAAAAAIw4\/Wp61GVzBJUM\/s1600\/IMG_3234.JPG\" width=\"740\" height=\"1000\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>Mapa de \u00abThe Hermit\u00bb, suplemento del \u00ednclito Gary Gygax para d20 rese\u00f1ado en <a href=\"https:\/\/www.lamarcadeleste.com\/2009\/03\/hermit.html\" target=\"_blank\" rel=\"noopener noreferrer\">La Marca del Este<\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\">Si <em><strong>eso<\/strong> <\/em>puede estar en un m\u00f3dulo comercial por el que la gente paga, definitivamente cualquier cosa que yo haga estar\u00e1 bien.<\/p>\n<p style=\"text-align: left;\">Hala, un \u00abpero\u00bb menos&#8230; ahora a quitar otros tres o cuatrocientos m\u00e1s, jejeje.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los proyectos que tengo por ah\u00ed pululando en mi mente (y en el google docs) es el de crear un peque\u00f1o \u00abcaj\u00f3n de arena\u00bb al estilo de las West Marches de Ben Robbins o los Points of Light de Robert Conley y Dwayne Gillingham. Tengo los art\u00edculos, tengo las tablas, tengo el mapeador&#8230; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[113],"class_list":["post-476","post","type-post","status-publish","format-standard","hentry","category-rol","tag-vieja-escuela"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":5424,"url":"https:\/\/www.erekibeon.com\/blog\/participando-en-el-proyecto-hexcrawl-de-la-frikoteca\/","url_meta":{"origin":476,"position":0},"title":"Participando en el Proyecto Hexcrawl de la Frikoteca","author":"Erek\u00edbeon","date":"21\/06\/2013","format":false,"excerpt":"Efectivamente, como si no fuera poco el retraso que tengo en otros frentes (blog, proyectos personales, proyectos colaborativos, etc) ahora voy y me lanzo a colaborar en el Proyecto Hexcrawl, una iniciativa de Carlos de la Cruz para crear entre muchos un sandbox de buen tama\u00f1o. En este momento estamos\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/mezclando_zpsa6b9ce09.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2738,"url":"https:\/\/www.erekibeon.com\/blog\/mapa-de-tiendas-de-rol-en-google-maps-colabora\/","url_meta":{"origin":476,"position":1},"title":"Mapa de tiendas de rol en Google Maps: \u00a1Colabora!","author":"Erek\u00edbeon","date":"27\/07\/2011","format":false,"excerpt":"Pues s\u00ed, amigos, llega el veranito y muchos nos desplazaremos a otras localidades para disfrutar del sol, la playa, la monta\u00f1a o lo que sea, tratando de encontrar un para\u00edso donde desconectar de nuestras ajetreadas y estresadas vidas. Pero \u00bfqu\u00e9 para\u00edso rolero estar\u00eda completo sin una tienda de rol cerca?\u2026","rel":"","context":"En \u00abFrikismo\u00bb","block_context":{"text":"Frikismo","link":"https:\/\/www.erekibeon.com\/blog\/category\/frikismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/maparol-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11993,"url":"https:\/\/www.erekibeon.com\/blog\/mapa-geopol-tico-por-a-os\/","url_meta":{"origin":476,"position":2},"title":"Mapa geopol\u00edtico por a\u00f1os","author":"Erek\u00edbeon","date":"11\/12\/2013","format":"link","excerpt":"Un atlas mundial donde se puede ir viendo c\u00f3mo van cambiando las fronteras a\u00f1o a a\u00f1o, desde el 3000 A.C hasta hoy en d\u00eda. Se aprecian estupendamente las conquistas, las anexiones, todito.","rel":"","context":"En \u00abHistoria\u00bb","block_context":{"text":"Historia","link":"https:\/\/www.erekibeon.com\/blog\/category\/historia\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2351,"url":"https:\/\/www.erekibeon.com\/blog\/oximoroneando-un-clasico-de-la-vieja-escuela-en-un-tablet-pc\/","url_meta":{"origin":476,"position":3},"title":"Oximoroneando: Un cl\u00e1sico de la Vieja Escuela en un tablet pc","author":"Erek\u00edbeon","date":"24\/03\/2011","format":false,"excerpt":"Hace alg\u00fan tiempo empec\u00e9 a arbitrar Aventuras en la Marca del Este con el grupo de Carlos de la Cruz, una experiencia que a\u00fan tengo que contar, lo s\u00e9 :-P. El caso es que despu\u00e9s de aquella partida, que me plante\u00e9 como un one-shot, necesitaba algo con m\u00e1s enjundia. Con\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2011-03-22213622.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2011-03-22213622.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2011-03-22213622.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2011-03-22213622.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":607,"url":"https:\/\/www.erekibeon.com\/blog\/inkwell-ideas\/","url_meta":{"origin":476,"position":4},"title":"Inkwell Ideas","author":"Erek\u00edbeon","date":"14\/07\/2009","format":false,"excerpt":"Bueno, hay muchos blogs de rol yankis que merece la pena seguir, pero \u00bfcu\u00e1ntos de ellos te ofrecen el mejor mapeador gratuito para crear mapas de la vieja escuela? Pues s\u00f3lo este. Por una parte tenemos el Hexographer, un mapeador en java que os recomiendo que prob\u00e9is. Tiene una gran\u2026","rel":"","context":"En \u00abOtros blogs\u00bb","block_context":{"text":"Otros blogs","link":"https:\/\/www.erekibeon.com\/blog\/category\/otros-blogs\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/hexographer.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":107,"url":"https:\/\/www.erekibeon.com\/blog\/bergonia\/","url_meta":{"origin":476,"position":5},"title":"Bergonia","author":"Erek\u00edbeon","date":"24\/07\/2008","format":false,"excerpt":"Cuando uno busca mapas en internet, suele encontrar un mont\u00f3n de mundos de campa\u00f1a para juegos de rol: The Kyngdoms, Argyris (\u00e9ste buen\u00edsimo, por cierto) o Daegon. Lo que no es tan normal es encontrarse un mundo hecho por el mero placer de dise\u00f1ar, imaginar, escribir y dibujar. Sin el\u2026","rel":"","context":"En \u00abInternet\u00bb","block_context":{"text":"Internet","link":"https:\/\/www.erekibeon.com\/blog\/category\/cosas-de-internet\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}