{"id":298,"date":"2008-11-26T11:23:53","date_gmt":"2008-11-26T10:23:53","guid":{"rendered":"http:\/\/erekibeon.wordpress.com\/?p=298"},"modified":"2022-12-10T20:09:48","modified_gmt":"2022-12-10T19:09:48","slug":"nuevas-noticias-en-westeros","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/nuevas-noticias-en-westeros\/","title":{"rendered":"Nuevas noticias en Westeros"},"content":{"rendered":"<p>Pues hay un par de novedades relacionadas con la obra de George R.R. Martin que me gustar\u00eda dejar por aqu\u00ed.<\/p>\n<p>En primer lugar quer\u00eda hacerme eco de la noticia de la futura publicaci\u00f3n en castellano d<a href=\"https:\/\/www.greenronin.com\/sifrp\/\" target=\"_blank\" rel=\"noopener noreferrer\">el juego de rol de Canci\u00f3n de Hielo y Fuego<\/a> por parte de <a href=\"https:\/\/www.edgeent.com\/juegos\/coleccion\/cancion_de_hielo_y_fuego\" target=\"_blank\" rel=\"noopener noreferrer\">Edge Entertainment<\/a>, al que desde ya voy a ir buscando hueco en las abigarradas estanter\u00edas de mi exigua casa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21974\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/CDHYFportada_SP_zps3947bd7d.jpg\" alt=\"\" width=\"450\" height=\"583\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/CDHYFportada_SP_zps3947bd7d.jpg 450w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/CDHYFportada_SP_zps3947bd7d-232x300.jpg 232w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/CDHYFportada_SP_zps3947bd7d-116x150.jpg 116w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/CDHYFportada_SP_zps3947bd7d-324x420.jpg 324w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>Y en segundo lugar, una noticia que a\u00fan no he visto por ah\u00ed. Resulta que a mediados de este a\u00f1o tuve la idea de reservar el siguiente libro de la saga, <a href=\"https:\/\/es.wikipedia.org\/wiki\/A_Dance_with_Dragons\" target=\"_blank\" rel=\"noopener noreferrer\">A Dance with Dragons<\/a>, en <a href=\"https:\/\/www.amazon.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Amazon<\/a>. Peri\u00f3dicamente me mandan recordatorios de que hice ese pedido por si quiero seguir con \u00e9l. Pues bien, en el \u00faltimo me informan que seg\u00fan sus noticias el libro saldr\u00e1 <strong>entre noviembre y diciembre de 2009<\/strong>. Lo cual no es de extra\u00f1ar, con los \u00faltimos de viajes de Martin alrededor del mundo y que yo le agradezco desde lo m\u00e1s profundo de mi alma friki.<\/p>\n<p>En definitiva, podremos armarnos de paciencia para el siguiente libro mientras desarrollamos nuestras propias sagas al respecto. No suena mal como plan para el invierno que se sigue acercando&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues hay un par de novedades relacionadas con la obra de George R.R. Martin que me gustar\u00eda dejar por aqu\u00ed. En primer lugar quer\u00eda hacerme eco de la noticia de la futura publicaci\u00f3n en castellano del juego de rol de Canci\u00f3n de Hielo y Fuego por parte de Edge Entertainment, al que desde ya voy [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,9,26,12],"tags":[69,530],"class_list":["post-298","post","type-post","status-publish","format-standard","hentry","category-frikismo","category-libros","category-medieval","category-noticias","tag-libros-2","tag-rol"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":970,"url":"https:\/\/www.erekibeon.com\/blog\/libreria51\/","url_meta":{"origin":298,"position":0},"title":"Librer\u00eda51","author":"Erek\u00edbeon","date":"11\/02\/2010","format":false,"excerpt":"Hace unos d\u00edas Kaliber me se\u00f1al\u00f3 esta tienda virtual, cuya URL tiene un nombre de lo m\u00e1s curioso: https:\/\/www.cuentaconmiespada.com\/ Como ver\u00e9is, se trata de una tienda virtual al estilo de la Fundaci\u00f3n Kaufman o Dracotienda, pero en esta ocasi\u00f3n hay dos peculiaridades que la diferencian del resto. Una son los\u2026","rel":"","context":"En \u00abInternet\u00bb","block_context":{"text":"Internet","link":"https:\/\/www.erekibeon.com\/blog\/category\/cosas-de-internet\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":772,"url":"https:\/\/www.erekibeon.com\/blog\/habra-que-echarle-un-ojo-dread\/","url_meta":{"origin":298,"position":1},"title":"Habr\u00e1 que echarle un ojo: Dread.","author":"Erek\u00edbeon","date":"25\/11\/2009","format":false,"excerpt":"V\u00eda Gnomestew me he enterado de la existencia de este curioso juego de rol de terror. Y digo curioso porque, como leer\u00e9is, la mec\u00e1nica central no son dados sino una torre de Jenga. El sistema b\u00e1sico se explica en cuatro p\u00e1ginas, con las cuales casi puedes ponerte a jugar desde\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.regalos.es\/media\/catalog\/product\/cache\/4\/image\/1104x\/040ec09b1e35df139433887a97daa66f\/t\/u\/turmchenbau-regalos-es_4454-13894410.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.regalos.es\/media\/catalog\/product\/cache\/4\/image\/1104x\/040ec09b1e35df139433887a97daa66f\/t\/u\/turmchenbau-regalos-es_4454-13894410.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.regalos.es\/media\/catalog\/product\/cache\/4\/image\/1104x\/040ec09b1e35df139433887a97daa66f\/t\/u\/turmchenbau-regalos-es_4454-13894410.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1095,"url":"https:\/\/www.erekibeon.com\/blog\/5-12-the-manchurian-incident\/","url_meta":{"origin":298,"position":2},"title":"5.12 The Manchurian Incident","author":"Erek\u00edbeon","date":"23\/04\/2010","format":false,"excerpt":"Aunque he seguido por los blogs habituales todo el revuelo que se ha montado en el mundillo \u00faltimamente con OKGames, siempre me he mantenido al margen porque, francamente, no me ha tocado directamente. Pero hete aqu\u00ed que recibo un mail de Rub\u00e9 Rivera Cisneros aka Torquemada que creo que es\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1111,"url":"https:\/\/www.erekibeon.com\/blog\/aluvion-de-noticias-y-novedades-el-mundillo-se-mueve\/","url_meta":{"origin":298,"position":3},"title":"Aluvi\u00f3n de noticias y novedades. El mundillo se mueve.","author":"Erek\u00edbeon","date":"04\/05\/2010","format":false,"excerpt":"Ejem. Est\u00e1 llegando un momento en el que, al igual que el buen Cruz de Caminos, estoy temiendo que este blog se convierta en un mero tabl\u00f3n de noticias. Esto no s\u00f3lo me sirve como tir\u00f3n de orejas porque estoy vagueando cosa mala en el blog, sino que tambi\u00e9n significa\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/2.bp.blogspot.com\/_CbQVPSTbe3w\/S3aGk2SeVDI\/AAAAAAAALsE\/I7JdGAtDho4\/S1600-R\/logomarcadeleste.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4917,"url":"https:\/\/www.erekibeon.com\/blog\/arrancan-los-premios-de-la-rolesfera-2012\/","url_meta":{"origin":298,"position":4},"title":"Arrancan los Premios de la Rolesfera 2012","author":"Erek\u00edbeon","date":"30\/01\/2013","format":false,"excerpt":"Lo s\u00e9, no es una noticia nueva, pero como de momento s\u00f3lo estamos apuntados 20 jurados creo que viene bien volver a comentarlo. Que seguro que m\u00e1s de uno lo hab\u00e9is dejado para m\u00e1s tarde y se os ha olvidado ;-) Como recordar\u00e9is, la votaci\u00f3n de los Premios de la\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/12-1-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/12-1-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/12-1-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":81,"url":"https:\/\/www.erekibeon.com\/blog\/el-fin-de-la-revista-nosolorol\/","url_meta":{"origin":298,"position":5},"title":"El fin de la Revista Nosolorol","author":"Erek\u00edbeon","date":"20\/07\/2008","format":false,"excerpt":"La semana pasada los chicos de Nosolorol publicaban su \u00faltima revista electr\u00f3nica. Para m\u00ed es una mala noticia, una p\u00e9rdida muy notable, porque se acaban cinco a\u00f1os de tener cada mes una revista sobre rol que hojear. Si me pongo a pensar en la cantidad de ordenadores desde los que\u2026","rel":"","context":"En \u00abInternet\u00bb","block_context":{"text":"Internet","link":"https:\/\/www.erekibeon.com\/blog\/category\/cosas-de-internet\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/i580.photobucket.com\/albums\/ss247\/erekibeon\/LogoNSR-1.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=298"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/298\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}