{"id":2695,"date":"2011-07-13T23:48:25","date_gmt":"2011-07-13T21:48:25","guid":{"rendered":"http:\/\/erekibeon.com\/blog\/?p=2695"},"modified":"2022-12-17T09:27:25","modified_gmt":"2022-12-17T08:27:25","slug":"resaca-del-campamento-de-verano-de-steam","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/resaca-del-campamento-de-verano-de-steam\/","title":{"rendered":"Resaca del Campamento de Verano de Steam"},"content":{"rendered":"<p>Durante la primera semana de Julio a los de Steam se les ocurri\u00f3 la genial idea de organizar un \u00abcampamento de verano\u00bb del 30 de junio al 10 de Julio. Aparte de poder obtener unos \u00ablogros\u00bb especiales (casi todos ten\u00edan que ver con comprar tal o cual juego) canjeables por tont\u00e1s como mini-<a href=\"https:\/\/es.wikipedia.org\/wiki\/Contenido_de_descarga\" target=\"_blank\" rel=\"noopener\">DLCs<\/a> pintorescos, todos los d\u00edas hac\u00edan jugos\u00edsimas ofertas a las que era muy dif\u00edcil resistirse.<\/p>\n<p>Vamos, al menos yo no pude resistirme&#8230; y he aqu\u00ed la lista de cosicas en las que he acabado por picar, junto con los precios. Un intento como otro cualquiera de justificar mi ansia consumista \ud83d\ude1b<\/p>\n<figure id=\"attachment_22432\" aria-describedby=\"caption-attachment-22432\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22432 size-full\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707.jpg\" alt=\"\" width=\"800\" height=\"481\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707.jpg 800w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707-300x180.jpg 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707-150x90.jpg 150w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707-768x462.jpg 768w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707-696x418.jpg 696w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707-699x420.jpg 699w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-22432\" class=\"wp-caption-text\">Los dibujicos que pon\u00edan cada d\u00eda molaban un mont\u00f3n, con los personajes de los videojuegos que ese d\u00eda estaban de oferta en plan veraniego total. Buena forma de empezar el veranito, desde luego.<\/figcaption><\/figure>\n<h3 style=\"text-align: left;\"><a href=\"https:\/\/store.steampowered.com\/app\/220\/?snr=1_4_4__13\" target=\"_blank\" rel=\"noopener\">Half-Life 2 (1,74 \u20ac)<\/a><\/h3>\n<p>Cuatro a\u00f1os despu\u00e9s de que mi Reina me lo regalara por Reyes y que comprobara con horror que no ven\u00eda el c\u00f3digo para sortear el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Gesti\u00f3n_de_derechos_digitales\" target=\"_blank\" rel=\"noopener\">DRM<\/a> e instalarlo, por fin voy a poder jugar esta secuela de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Half-Life_%28videojuego%29\" target=\"_blank\" rel=\"noopener\">uno de los juegos<\/a> que figuran en lo m\u00e1s alto de mi pante\u00f3n particular. Ya era hora&#8230; ya era hora.<\/p>\n<h3><a href=\"https:\/\/store.steampowered.com\/app\/3590\/?snr=1_5_9__13\" target=\"_blank\" rel=\"noopener\">Plants vs. Zombies (3,39 \u20ac)<\/a><\/h3>\n<p>Siempre he tenido curiosidad por este t\u00edtulo, no s\u00f3lo porque tenga la palabra \u00abZombies\u00bb en su t\u00edtulo (que tambi\u00e9n :-P) sino porque\u00a0 hab\u00eda escuchado cr\u00edticas positivas y ten\u00eda pinta de ser el t\u00edpico juego \u00abcasual\u00bb ideal para poder darle ca\u00f1a mientras veo mi cap\u00edtulo\u00a0 nocturno de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Stargate_SG-1\" target=\"_blank\" rel=\"noopener\">Stargate SG-1<\/a> \ud83d\ude1b<\/p>\n<p>Al final no ha resultado un mal juego, pero aun estando de rebajas me ha parecido un poco caro. Es un ejemplo como el de <a href=\"https:\/\/www.google.es\/url?sa=t&amp;source=web&amp;cd=1&amp;ved=0CCQQFjAA&amp;url=http%3A%2F%2Fchrome.angrybirds.com%2F&amp;rct=j&amp;q=angry%20birds&amp;ei=0HsdTvi3BYeVOvq4kLIJ&amp;usg=AFQjCNHU091bFQKPkmK5ZUEH3vaoQAkXzw&amp;sig2=CwOvlPfhfNIKdb-CQVnNTA&amp;cad=rja\" target=\"_blank\" rel=\"noopener\">Angry Birds<\/a>: darle una vuelta de tuerca a un concepto de juego que ya exist\u00eda en juegos indies (en este caso el <a href=\"https:\/\/es.wikipedia.org\/wiki\/Tower_defense\" target=\"_blank\" rel=\"noopener\">Tower Defense<\/a>), a\u00f1adi\u00e9ndole gr\u00e1ficos simp\u00e1ticos y agregando fases rarunas y minijuegos para que no te aburras.<\/p>\n<p>Fijaos si habr\u00e1 tenido \u00e9xito que gracias a este jueguecico <a href=\"https:\/\/www.elmundo.es\/elmundo\/2011\/07\/13\/navegante\/1310554922.html\" target=\"_blank\" rel=\"noopener\">EA acaba de comprar la empresa que lo cre\u00f3<\/a>&#8230;<\/p>\n<h3><a href=\"https:\/\/store.steampowered.com\/app\/42910\/\" target=\"_blank\" rel=\"noopener\">Magicka (3,39 \u20ac)<\/a><\/h3>\n<p>Otro t\u00edtulo que me suscitaba cierta curiosidad, no tanto por el concepto (magos lanzando hechizos a diestro y siniestro) sino por los DLCs tan \u00bfPQC? que se anunciaban de vez en cuando, como el <a href=\"https:\/\/store.steampowered.com\/app\/42918\/\" target=\"_blank\" rel=\"noopener\">Magicka: Vietnam<\/a>. Lo he jugado cinco minutillos nada m\u00e1s, pero mis primeras impresiones son buenas: me encanta la facilidad con la que se invocan las distintas magias y las inmensas posibilidades de combinaci\u00f3n, y tambi\u00e9n me hace gracia el ambiente gamberro del juego. Con deciros que mi personaje lleva, adem\u00e1s de la t\u00fanica y el cayado, un traje con corbata y una pistola&#8230;<\/p>\n<p>En fin, habr\u00e1 que probar el modo cooperativo un d\u00eda de estos, a ver qu\u00e9 tal.<\/p>\n<h3><a href=\"https:\/\/store.steampowered.com\/app\/10680\/?snr=1_5_9__13\" target=\"_blank\" rel=\"noopener\">Aliens vs Predator (4,99 \u20ac)<\/a><\/h3>\n<p>Uno de esos <a href=\"https:\/\/es.wikipedia.org\/wiki\/Videojuego_de_disparos_en_primera_persona\" target=\"_blank\" rel=\"noopener\">FPS<\/a> que me llamaron la atenci\u00f3n en su momento, pero que nunca me pill\u00e9 porque las cr\u00edticas lo pon\u00edan m\u00e1s bien como regulero. Pero siempre me ha gustado la idea de llevar un Predator, as\u00ed que por ese precio le voy a dar un tiento.<\/p>\n<h3><a href=\"https:\/\/store.steampowered.com\/app\/41500\/\" target=\"_blank\" rel=\"noopener\">Torchlight (2,99 \u20ac)<\/a><\/h3>\n<p>No confundir con Torchwood, que me a m\u00ed me ha pasado \ud83d\ude1b Este t\u00edtulo me lo apunt\u00e9 tras leer <a href=\"https:\/\/rampantgames.com\/blog\/?p=841\" target=\"_blank\" rel=\"noopener\">este art\u00edculo<\/a> de <a href=\"https:\/\/rampantgames.com\/blog\/\" target=\"_blank\" rel=\"noopener\">Tales of the Rampant Coyote<\/a> donde lo comparaban con el m\u00edtico Diablo II. A\u00fan no lo he probado para ver si aguanta tal aseveraci\u00f3n, pero 3 euros me parecen justos para un juego a priori tan currado.<\/p>\n<h3><a href=\"https:\/\/store.steampowered.com\/app\/55040\/?snr=1_5_9__13\" target=\"_blank\" rel=\"noopener\">Atom Zombie Smasher (2,99 \u20ac)<\/a><\/h3>\n<p>S\u00ed, amigos, otro juego con la palabra \u00abZombie\u00bb en el t\u00edtulo, y con el que ya me he enganchado un par de veces.<\/p>\n<p>\u00bfOs acord\u00e1is de <a href=\"https:\/\/kevan.org\/proce55ing\/zombies\/\" target=\"_blank\" rel=\"noopener\">esta simulaci\u00f3n de infecci\u00f3n zombi<\/a>? Pues alguien ha debido tomarla como referencia para crear un juego, y le ha quedado bastante curioso. Somos los responsables de evacuar a la poblaci\u00f3n de varias ciudades antes de que la marea zombi les devore a todos, y para ello contaremos con un helic\u00f3ptero y varios recursos para intentar retrasar el avance de los muertos vivientes: Minas, barricadas, equipos de asalto cercano, se\u00f1uelos, francotiradores&#8230; Adem\u00e1s tiene un componente estrat\u00e9gico, ya que ir\u00e1s viendo sobre un mapa regional el alcance de la infecci\u00f3n y tendr\u00e1s que decidir d\u00f3nde intervenir, teniendo tambi\u00e9n en cuenta que no siempre cuentas con todos los recursos.<\/p>\n<p>Sencillote pero adictivo, la verdad.<\/p>\n<figure id=\"attachment_22431\" aria-describedby=\"caption-attachment-22431\" style=\"width: 1009px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22431 size-full\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002.png\" alt=\"\" width=\"1009\" height=\"834\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002.png 1009w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002-300x248.png 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002-150x124.png 150w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002-768x635.png 768w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002-696x575.png 696w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/Snap_20110317_14h33m04s_002-508x420.png 508w\" sizes=\"auto, (max-width: 1009px) 100vw, 1009px\" \/><figcaption id=\"caption-attachment-22431\" class=\"wp-caption-text\">Los puntos morados son los zombis, los amarillos la poblaci\u00f3n civil&#8230; y tu helic\u00f3ptero s\u00f3lo tiene 30 plazas. Ahora sabr\u00e1s lo que se siente al tener la vida de inocentes puntitos amarillos en tus manos&#8230;<\/figcaption><\/figure>\n<p style=\"text-align: center;\">\n<p><span style=\"font-size: 21px; line-height: 23px;\"><a href=\"https:\/\/store.steampowered.com\/sub\/553\/\" target=\"_blank\" rel=\"noopener\">Company of Heroes Gold (3,74 \u20ac)<\/a><\/span><\/p>\n<p>\u00c9sta fue una compra por impulso, tal cual. La \u00fanica justificaci\u00f3n es que el planteamiento me record\u00f3 poderosamente al <a href=\"https:\/\/en.wikipedia.org\/wiki\/Close_Combat_(video_game)\" target=\"_blank\" rel=\"noopener\">Close Combat<\/a> con el que tanto me divert\u00ed en su momento. Aunque por las cr\u00edticas que he le\u00eddo no ha sido mala compra, y menos a ese precio&#8230;<\/p>\n<p>En fin, ya veis, horas y horas de entretenimiento digital por menos de lo que cuesta hoy d\u00eda un manual rolero de gama media. Otra cosa es que tenga tiempo para estar a todo, claro \ud83d\ude1b<\/p>\n<p>Ah, y por si tambi\u00e9n est\u00e1is en Steam y quer\u00e9is encontrarme por all\u00ed para echarnos alguna partidilla de vez en cuando, <a href=\"https:\/\/steamcommunity.com\/id\/erekibeon\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed ten\u00e9is mi perfil<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la primera semana de Julio a los de Steam se les ocurri\u00f3 la genial idea de organizar un \u00abcampamento de verano\u00bb del 30 de junio al 10 de Julio. Aparte de poder obtener unos \u00ablogros\u00bb especiales (casi todos ten\u00edan que ver con comprar tal o cual juego) canjeables por tont\u00e1s como mini-DLCs pintorescos, todos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[22],"tags":[102,111],"class_list":["post-2695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos","tag-steam","tag-videojuegos-2"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":169,"url":"https:\/\/www.erekibeon.com\/blog\/steam-database\/","url_meta":{"origin":2695,"position":0},"title":"Steam Database","author":"Erek\u00edbeon","date":"01\/07\/2014","format":false,"excerpt":"Curiosa herramienta online para controlar muchas cosas relacionadas con Steam: desde averiguar cu\u00e1nta pasta gansa vale tu cuenta\u00a0(y descubrir el\u00a0fortun\u00f3n que tienes invertido ah\u00ed) hasta controlar de forma sencilla las ofertas, lo que viene estupendamente durante las famosas rebajas de Steam (de verano y de invierno)","rel":"","context":"En \u00abTrastero\u00bb","block_context":{"text":"Trastero","link":"https:\/\/www.erekibeon.com\/blog\/category\/trastero\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5501,"url":"https:\/\/www.erekibeon.com\/blog\/autoindulgencia\/","url_meta":{"origin":2695,"position":1},"title":"Autoindulgencia","author":"Erek\u00edbeon","date":"08\/08\/2013","format":false,"excerpt":"es un sin\u00f3nimo de \u00a0\"holgazaner\u00eda\" con mucho m\u00e1s glamour, d\u00f3nde va a parar. Pero ambos definen a la perfecci\u00f3n el estado en el que estoy ahora mismo. \u00a0:-P Y es que me he dado cuenta de que, seg\u00fan el calendario que hay en la columna derecha del blog, llevo casi\u2026","rel":"","context":"En \u00abLibros\u00bb","block_context":{"text":"Libros","link":"https:\/\/www.erekibeon.com\/blog\/category\/libros\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/1224913-justcause2_nov13_6_11122009_6_zps98e8d04b.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/1224913-justcause2_nov13_6_11122009_6_zps98e8d04b.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/1224913-justcause2_nov13_6_11122009_6_zps98e8d04b.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/1224913-justcause2_nov13_6_11122009_6_zps98e8d04b.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":240,"url":"https:\/\/www.erekibeon.com\/blog\/fantasmadas-de-accion-que-me-molan-saints-row-3\/","url_meta":{"origin":2695,"position":2},"title":"Fantasmadas de acci\u00f3n que me molan: Saints Row 3","author":"Erek\u00edbeon","date":"27\/11\/2014","format":false,"excerpt":"Este verano pill\u00e9 un bundle de Steam de Saints Row, lleno de curiosidad porque la gente\u00a0 pon\u00eda la \u00faltima entrega (la 4) por las nubes. Y lo cierto es que me divert\u00ed tanto con las fantasmadas de Saints Row IV y su humor cafre que quise remontarme en la saga\u2026","rel":"","context":"En \u00abTrastero\u00bb","block_context":{"text":"Trastero","link":"https:\/\/www.erekibeon.com\/blog\/category\/trastero\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/vBkCfVyYFdU\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14581,"url":"https:\/\/www.erekibeon.com\/blog\/battletech-los-violentos-barbagrises\/","url_meta":{"origin":2695,"position":3},"title":"Battletech: Los Violentos Barbagrises","author":"Erek\u00edbeon","date":"03\/09\/2018","format":"video","excerpt":"Perdonen las disculpas, pero es que ten\u00eda que hacerle un v\u00eddeo a Battletech. No me quedaba otra. Y es que \u00bfqu\u00e9 pod\u00eda hacer? Soy m\u00e1s fan de los videojuegos de este universo que de los juegos de tablero o del juego de rol (aunque los tengo). As\u00ed que cuando anunciaron\u2026","rel":"","context":"En \u00abVideojuegos\u00bb","block_context":{"text":"Videojuegos","link":"https:\/\/www.erekibeon.com\/blog\/category\/videojuegos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/09\/maxresdefault.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/09\/maxresdefault.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/09\/maxresdefault.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/09\/maxresdefault.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2018\/09\/maxresdefault.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3587,"url":"https:\/\/www.erekibeon.com\/blog\/4-anos-sin-gary-gygax-dia-del-master-y-marzo-negro\/","url_meta":{"origin":2695,"position":4},"title":"4 a\u00f1os sin Gary Gygax, d\u00eda del M\u00e1ster y Marzo Negro","author":"Erek\u00edbeon","date":"04\/03\/2012","format":false,"excerpt":"Tal d\u00eda como hoy de hace 4 a\u00f1os nos dej\u00f3 el Primer M\u00e1ster. Y como vengo haciendo desde el primer aniversario, he hecho una tirada de un d20 en su honor. \u00c9ste es el resultado para este a\u00f1o: \u00a1Casi un cr\u00edtico! Ch\u00fapate esa, caballero en armadura completa, \u00f1ej \u00f1ej \u00f1ej.\u2026","rel":"","context":"En \u00abFrikismo\u00bb","block_context":{"text":"Frikismo","link":"https:\/\/www.erekibeon.com\/blog\/category\/frikismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/TiradaGygax2012.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11999,"url":"https:\/\/www.erekibeon.com\/blog\/10-roguelikes-gratuitos-para-morir-el-pixel-ilustre\/","url_meta":{"origin":2695,"position":5},"title":"10 roguelikes gratuitos para morir \u00bb El Pixel Ilustre","author":"Erek\u00edbeon","date":"15\/07\/2013","format":"link","excerpt":"10 roguelikes gratuitos para morir \u00bb El Pixel IlustreDescubierto v\u00eda The Freak Times, algunos roguelikes a los que tendr\u00e9 que dedicarles un tiempo\u2026 mientras no me lo impidan las rebajas de Steam, claro :-P","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/for_release_707.jpg","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/2695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=2695"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/2695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media\/22432"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=2695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=2695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=2695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}