{"id":2218,"date":"2011-01-14T15:59:52","date_gmt":"2011-01-14T13:59:52","guid":{"rendered":"http:\/\/erekibeon.com\/blog\/?p=2218"},"modified":"2022-12-14T18:51:39","modified_gmt":"2022-12-14T17:51:39","slug":"en-el-2%c2%ba-debate-del-estado-de-la-nacion-rolera","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/en-el-2%c2%ba-debate-del-estado-de-la-nacion-rolera\/","title":{"rendered":"En el 2\u00ba Debate del Estado de la Naci\u00f3n Rolera"},"content":{"rendered":"<p>Pues \u00a1menuda forma de empezar el a\u00f1o! Todav\u00eda no me lo creo. Y es que, cuando me lleg\u00f3 la invitaci\u00f3n de Kane, lo primero que me vino a la cabeza fue el nombre de un mont\u00f3n de gente mucho m\u00e1s capacitada para dar la r\u00e9plica a los mism\u00edsimos <strong><a href=\"https:\/\/radiotelperion.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kane, Absolom,<\/a> <a href=\"https:\/\/elopinometro.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Avatar<\/a>, <a href=\"https:\/\/web.archive.org\/web\/20200711184300\/https:\/\/www.demoniosonriente.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Zonk<\/a>, <a href=\"https:\/\/web.archive.org\/web\/20140527100001\/https:\/\/www.rolgratis.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Meroka<\/a>, <a href=\"https:\/\/web.archive.org\/web\/20151101052658\/https:\/\/spqrol.com:80\/foro\/index.php?action=profile;u=1\" target=\"_blank\" rel=\"noopener noreferrer\">Bandido<\/a> y <a href=\"https:\/\/ludotecnia.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">AK-47<\/a><\/strong>. Es decir, iban a estar editores, creadores, gente con proyectos s\u00f3lidos, consolidados y con mucha trayectoria en el mundillo&#8230; y yo, que lo \u00fanico que he hecho ha sido un blog y una colaboraci\u00f3n en una traducci\u00f3n de \u00a112 p\u00e1ginas!. T\u00f3cate los webs, Mariloli.<\/p>\n<p>Vamos, que ten\u00eda razones para estar nervioso, mi primera vez que iba a una radio y encima con gente de ese nivel. Si la cagaba a ver con qu\u00e9 cara iba a aparecer yo por aqu\u00ed \ud83d\ude1b Que una cosa es desbarrar delante de unas cervezas y otra hacerlo con micr\u00f3fonos por delante y una grabaci\u00f3n que permanecer\u00e1 para siempre jam\u00e1s&#8230;<\/p>\n<p>Pero lo cierto es que al llegar a <a href=\"https:\/\/radiotelperion.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Radio Arrebato<\/a> se disiparon todos mis temores y nerviosismos. Ya conoc\u00eda a Avatar, Absolom y Kane de las pasadas reuniones de la SGRI, y Bandido y Meroka resultaron ser igual de abiertos y accesibles, con lo que pr\u00e1cticamente la conversaci\u00f3n surgi\u00f3 por s\u00ed sola. Aunque siempre me quedar\u00e1 la duda de por d\u00f3nde habr\u00eda ido el debate si AK-47 hubiera podido estar&#8230; (un saludo desde aqu\u00ed y espero que os mejor\u00e9is, maestro).<\/p>\n<p style=\"text-align: left;\">El resultado <a href=\"https:\/\/www.ivoox.com\/telperion-12-enero-2-011-audios-mp3_rf_488558_1.html\" target=\"_blank\" rel=\"noopener noreferrer\">ya lo hab\u00e9is escuchado<\/a>. Y no s\u00e9 si ser\u00e1 cosa m\u00eda, pero me da la sensaci\u00f3n de que se empieza con posturas que parecen muy distintas y que para el final del debate hay bastante consenso. As\u00ed que tal vez la idea de Zonk sobre hacer una reuni\u00f3n mucho mayor con muchos m\u00e1s interlocutores (otros editores, miembros de clubs, organizadores de jornadas, etc) no sea tan descabellada, despu\u00e9s de todo&#8230; Eso s\u00ed, mejor realizarla en una sala de actos o algo as\u00ed, porque el estudio de Radio Arrebato es realmente peque\u00f1o.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22292\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n.jpg\" alt=\"\" width=\"604\" height=\"453\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n.jpg 604w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n-300x225.jpg 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n-150x113.jpg 150w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n-560x420.jpg 560w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n-80x60.jpg 80w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n-160x120.jpg 160w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n-265x198.jpg 265w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22291\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n.jpg\" alt=\"\" width=\"604\" height=\"453\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n.jpg 604w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n-300x225.jpg 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n-150x113.jpg 150w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n-560x420.jpg 560w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n-80x60.jpg 80w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n-160x120.jpg 160w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412193213750_100000349085881_34751_6902209_n-265x198.jpg 265w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/p>\n<p style=\"text-align: center;\">\n<p><strong><em>En esa mesa de la foto de abajo es donde est\u00e1bamos Meroka, Avatar, Bandido y yo. Dicen que el roce hace el cari\u00f1o, jejejej \ud83d\ude1b (Foto procedente del <a href=\"https:\/\/radiotelperion.blogspot.com.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">perfil de Radio Telperion en Facebook<\/a>)<\/em><\/strong><\/p>\n<p>Por mi parte, yo sal\u00ed con muchos m\u00e1s matices en la cabeza. Le doy la raz\u00f3n a Meroka cuando dice que los aficionados deber\u00edamos seguir demostrando que hay un mercado vivo y con posibilidades de negocio. No hay m\u00e1s que ver lo que pasa en Barcelona con el <a href=\"https:\/\/clubkritik.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Club Kritik<\/a>, como bien dec\u00eda <a href=\"https:\/\/wedworlds.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Wed<\/a> en los <a href=\"https:\/\/www.blogger.com\/comment.g?blogID=464194665929701829&amp;postID=7876834862304984541&amp;isPopup=true\" target=\"_blank\" rel=\"noopener noreferrer\">comentarios del blog<\/a>, para ver que las editoriales suelen acompa\u00f1ar esos movimientos. Incluso NSR y Sombra est\u00e1n montando sus propias jornadas, pero a\u00fan estamos lejos de una GenCon o de un E3, tal vez porque, como dicen Avatar y Kane, no hay un \u00absector\u00bb suficientemente fuerte como para organizarlas. Aunque no estar\u00eda de m\u00e1s que las editoriales que hay ahora mismo, todas, colaboraran e impulsaran juntas tambi\u00e9n alguna iniciativa.<\/p>\n<p>Por otro lado, sigo pensando que una federaci\u00f3n o una asociaci\u00f3n nacional dar\u00eda mucha m\u00e1s visibilidad y credibilidad a esta afici\u00f3n, no s\u00f3lo para organizar actos y dem\u00e1s, sino tambi\u00e9n para ayudar a que el mundillo se cohesione.\u00a0 De acuerdo, hay un mont\u00f3n de gur\u00fas, pero \u00bfcu\u00e1ntos gur\u00fas de Internet hay por ah\u00ed? Seguro que varios cientos de miles m\u00e1s. Y oye, hay una Asociaci\u00f3n de Internautas&#8230;<\/p>\n<p>Para m\u00ed uno de los ejemplos m\u00e1s patentes de que es posible organizar a tropecientos gur\u00fas roleros son los <a href=\"https:\/\/rolesfera.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Premios de la Rolesfera<\/a>, los Poliedro. Su creaci\u00f3n no fue f\u00e1cil, pero en cuanto echaron a rodar la cosa ha ido para arriba, aunque la organizaci\u00f3n este a\u00f1o se la est\u00e9 currando <a href=\"https:\/\/besterbrainstormer.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bester<\/a> cosa mala&#8230; Que s\u00ed, que es gratis y no hay cuotas y que tal y que pascual, pero creo que es un peque\u00f1o paso. Otro ejemplo lo tenemos con la movida del cierre de Radio Telperion, \u00bfos acord\u00e1is de c\u00f3mo se organiz\u00f3 el mundillo espont\u00e1nteamente?. Pues todas estas cosas est\u00e1n creando comunidad, poquito a poco. En mi opini\u00f3n, s\u00f3lo es cuesti\u00f3n de tiempo el que algo m\u00e1s formal cristalice, siempre que se aborde el tema con madurez y con responsabilidad. Que sirvan para algo los a\u00f1itos que m\u00e1s de uno ya tenemos, y que sirvan tambi\u00e9n la experiencia de todos esos clubs de largo recorrido y de esos organizadores de jornadas, que tambi\u00e9n tienen mucho que aportar.<\/p>\n<p>Y s\u00f3lo una peque\u00f1a disculpa: lo reconozco, soy muy pesado con el juego de rol de \u00c1guila Roja \ud83d\ude1b Pero es que sigo pensando que se ha perdido una magn\u00edfica oportunidad de acercar el rol al gran p\u00fablico. \u00bfQue la premisa de la serie es injugable? No s\u00e9, yo ve\u00eda m\u00e1s dif\u00edcil hacer un juego de Buffy o de Smallville, y ah\u00ed est\u00e1n. Y si encima te curras un buen manual, lleno de im\u00e1genes exclusivas, con arte conceptual y buena presencia, estoy seguro de que una parte de la audiencia de la serie (recordemos, una parte de \u00a1casi 3 millones de personas!) se har\u00eda con \u00e9l. Entre otras cosas porque a\u00fan no hay un libro de fotos y arte sobre la serie, como s\u00ed los hubo del Se\u00f1or de los Anillos, por ejemplo, y el juego de rol tambi\u00e9n podr\u00eda servir para ocupar ese nicho. \u00bfNo se trataba de ampliar la base de jugadores? Pues no se me ocurre ninguna otra oportunidad tan, tan clara como \u00e9sta en Espa\u00f1a. Y es una l\u00e1stima.<\/p>\n<p>En fin, que estoy totalmente a favor de que haya un debate mucho m\u00e1s grande, con gente de m\u00e1s relevancia y todo eso. Pero para m\u00ed \u00e9ste ha sido toda una experiencia y me ha encantado vivirla. Gracias, maestres Kane y Absolom, por la oportunidad y por la hospitalidad. A la Sra. V. por invitarse a las ca\u00f1as y raciones de despu\u00e9s, \u00a1faltar\u00eda m\u00e1s!, y al resto de contertulios por haberme dejado sobrevivir, jajajaja. ^.^ Todo un placer, se\u00f1ores, \u00a1un abrazo a los cuatro!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues \u00a1menuda forma de empezar el a\u00f1o! Todav\u00eda no me lo creo. Y es que, cuando me lleg\u00f3 la invitaci\u00f3n de Kane, lo primero que me vino a la cabeza fue el nombre de un mont\u00f3n de gente mucho m\u00e1s capacitada para dar la r\u00e9plica a los mism\u00edsimos Kane, Absolom, Avatar, Zonk, Meroka, Bandido y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[30,51,96,98],"class_list":["post-2218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frikismo","tag-aguila-roja","tag-evangelizacion","tag-rol-gratis","tag-rolesfera"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":775,"url":"https:\/\/www.erekibeon.com\/blog\/inscrito-en-el-curso-de-escritura-rolera\/","url_meta":{"origin":2218,"position":0},"title":"Inscrito en el curso de escritura rolera","author":"Erek\u00edbeon","date":"29\/10\/2009","format":false,"excerpt":"\u00a1\u00a1S\u00ed, a m\u00ed tambi\u00e9n me han aceptado!! A ver qu\u00e9 tal se me dan los deberes... Por si acaso alguien no se ha enterado (que lo dudo), se trata del Curso que va a impartir Pedro J. Ramos, y cuyos resultados va a ir colgando en su blog Veinticinco. Esto\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"Banner del curso","src":"https:\/\/i0.wp.com\/3.bp.blogspot.com\/_fcS6iraHfWM\/SuWUe_jcJ6I\/AAAAAAAAAX0\/mRAVE0T05Z4\/s320\/FAMA2.JPG?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2589,"url":"https:\/\/www.erekibeon.com\/blog\/microscopia-en-tesoros-de-la-marca\/","url_meta":{"origin":2218,"position":1},"title":"Microscopia en Tesoros de la Marca","author":"Erek\u00edbeon","date":"02\/06\/2011","format":false,"excerpt":"El maestro Scribble me ha chivado que desde hace poco Tesoros de la Marca tiene disponibles \u00a1en exclusiva! los \u00faltimos ejemplares de su obra, Microscopia. Como sab\u00e9is, al principio este stock estaba en la Fundaci\u00f3n Kauffman, pero desde su cierre Scribble empez\u00f3 a venderlo por ebay. Un servidor tuvo que\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/imagenes_Hormigaz_1_79d175b8.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2395,"url":"https:\/\/www.erekibeon.com\/blog\/un-primer-vistazo-a-la-nueva-edicion-de-aquelarre\/","url_meta":{"origin":2218,"position":2},"title":"Un primer vistazo a la nueva edici\u00f3n de Aquelarre","author":"Erek\u00edbeon","date":"31\/03\/2011","format":false,"excerpt":"Pues antesdeayer recib\u00ed por fin la nueva edici\u00f3n de Aquelarre, pero hasta ayer no pude dedicarle tiempo a hacerle una videorrese\u00f1a como es debido para que ve\u00e1is (\u00a1y escuch\u00e9is!) c\u00f3mo es f\u00edsicamente el libro. Y aqu\u00ed la ten\u00e9is. https:\/\/www.youtube.com\/watch?v=bIZNy5z2yno Sobre el contenido, pues me reafirmo en lo que coment\u00e9 en\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2090,"url":"https:\/\/www.erekibeon.com\/blog\/la-presentacion-de-la-marca-del-este-en-madrid\/","url_meta":{"origin":2218,"position":3},"title":"La presentaci\u00f3n de La Marca del Este en Madrid","author":"Erek\u00edbeon","date":"20\/12\/2010","format":false,"excerpt":"\"Recuerda este d\u00eda, hermano menor. Hoy la vida es buena\". Esta frase de Boromir me parece que es la que mejor describe mis sensaciones tras el pedazo de d\u00eda que pas\u00e9 el s\u00e1bado. Como comentaba en el Facebook al llegar a casa, dudo que haya d\u00edas m\u00e1s completos para un\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/www.erekibeon.com\/blog\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/IMG00075-20101218-1728.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/IMG00075-20101218-1728.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/IMG00075-20101218-1728.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/IMG00075-20101218-1728.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1980,"url":"https:\/\/www.erekibeon.com\/blog\/20-anos-de-aquelarre\/","url_meta":{"origin":2218,"position":4},"title":"20 a\u00f1os de Aquelarre","author":"Erek\u00edbeon","date":"19\/11\/2010","format":false,"excerpt":"Llego un poco tarde a esta celebraci\u00f3n que han empezado Antonio Polo, Carlos de la Cruz o\u00a0Kano o \u00a0(aunque, curiosamente, el goblin \u00a1nunca lo ha jugado! :-O) pero bueno, dicen que m\u00e1s vale tarde que nunca :-P Hablar de Aquelarre es remontarme a cuando ten\u00eda 16 a\u00f1os y me hice\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/HIMYMkids.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/HIMYMkids.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/HIMYMkids.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":725,"url":"https:\/\/www.erekibeon.com\/blog\/mas-monstruos-en-leganes\/","url_meta":{"origin":2218,"position":5},"title":"M\u00e1s monstruos en Legan\u00e9s","author":"Erek\u00edbeon","date":"05\/10\/2009","format":false,"excerpt":"Al igual que Dacostilla en su blog \"Al M\u00e1ster Desconocido\", Carlos de la Cruz en su blog \"La Frikoteca\", Vardita en su \"Proyecto RPG\" o Kano en sus \"Historias de un Goblin en el mundo moderno\" yo tambi\u00e9n he tenido el honor de recibir una solicitud de Raven Stalk para\u2026","rel":"","context":"En \u00abFrikismo\u00bb","block_context":{"text":"Frikismo","link":"https:\/\/www.erekibeon.com\/blog\/category\/frikismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/2.bp.blogspot.com\/_-P4uGBn8QYw\/Sr8-Qx-NNqI\/AAAAAAAAAFI\/efxiyAv2eaI\/s1600\/cartel%2Breducido.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/8921_101412186547084_100000349085881_34749_3425667_n.jpg","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/2218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=2218"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/2218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media\/22292"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=2218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=2218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=2218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}