{"id":1785,"date":"2010-10-04T12:51:30","date_gmt":"2010-10-04T10:51:30","guid":{"rendered":"http:\/\/erekibeon.com\/blog\/?p=1785"},"modified":"2022-12-13T18:56:30","modified_gmt":"2022-12-13T17:56:30","slug":"dd-essentials-vs-ame","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/dd-essentials-vs-ame\/","title":{"rendered":"D&#038;D Essentials vs AME"},"content":{"rendered":"<p>La otra pol\u00e9mica del verano, aunque en esta ocasi\u00f3n creo que ha sido un c\u00famulo de malentendidos. Nunca he sido muy fan de Devir, pero eso de pensar que hayan contraprogramado las Aventuras de la Marca del Este con la Caja Roja&#8230; pufff. Dada su historia de no hacer ni caso al aficionado o a lo que se cuece en el mundillo, me parece m\u00e1s l\u00f3gico pensar que lo \u00fanico que ha hecho Devir ha sido seguir el calendario de Wizards of the Coast, ni m\u00e1s ni menos. Pero en fin,\u00a0 igual es que soy demasiado inocente en estas lides.<\/p>\n<p>Yo tambi\u00e9n tengo un problema con este tema, pero es m\u00e1s terrenal. Creo que ya lo he comentado en otras ocasiones, pero mi casa de 60 metros cuadrados con dos habitaciones + princesa y sin trastero se est\u00e1 quedando corta para seguir dando rienda suelta a los, como dir\u00eda <a href=\"https:\/\/gonzix.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gonzix<\/a>, \u00abimpulsos hamsteriles roleros\u00bb. No puedo permitirme seguir acumulando juegos voluminosos. As\u00ed que, de las dos cajas aspirantes (redoble de tambores)&#8230; \u00a1s\u00f3lo puede caber una!<\/p>\n<p>Ech\u00e9mosle un ojo de cerca a las competidoras por el hueco entre la tele y la Tumba de los Horrores&#8230;<\/p>\n<h3>Componentes<\/h3>\n<p><strong>D&amp;D Esenciales<\/strong><\/p>\n<figure id=\"attachment_22238\" aria-describedby=\"caption-attachment-22238\" style=\"width: 288px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-22238 size-full\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/caja-roja.jpg\" alt=\"\" width=\"288\" height=\"378\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/caja-roja.jpg 288w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/caja-roja-229x300.jpg 229w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/caja-roja-114x150.jpg 114w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><figcaption id=\"caption-attachment-22238\" class=\"wp-caption-text\">N\u00f3tese la etiqueta de \u00abDevir\u00bb ah\u00ed, bien visible, marcando la esquina.<\/figcaption><\/figure>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22239\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/dnd4-cajaroja_contenido.jpg\" alt=\"\" width=\"455\" height=\"566\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/dnd4-cajaroja_contenido.jpg 455w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/dnd4-cajaroja_contenido-241x300.jpg 241w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/dnd4-cajaroja_contenido-121x150.jpg 121w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/dnd4-cajaroja_contenido-338x420.jpg 338w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><\/p>\n<p>Seg\u00fan <a href=\"https:\/\/web.archive.org\/web\/20130706235426\/https:\/\/www.devir.es\/producto\/caja-roja-de-dd\" target=\"_blank\" rel=\"noopener noreferrer\">la web de Devir<\/a>, y el nuevo<a href=\"https:\/\/zjordi.blogspot.com\/2010\/09\/la-caja-roja-en-vivo-y-en-directo.html\" target=\"_blank\" rel=\"noopener noreferrer\"> blog de Jordi Zamarre\u00f1o<\/a>, estos son los componentes de la caja:<\/p>\n<ul>\n<li>Libro de juego del Dungeon Master (64 p\u00e1ginas), con las reglas de juego (sistema similar a la 4\u00aa ed), y contenido de aventuras para h\u00e9roes de niveles 1 y 2.<\/li>\n<li>Libro del jugador, (32 p\u00e1ginas) que contiene las reglas de creaci\u00f3n de h\u00e9roes y una aventura en solitario.<\/li>\n<li>Una hoja de fichas de cart\u00f3n troquelado a doble cara, representando a los h\u00e9roes y los monstruos.<\/li>\n<li>Hoja de personaje y 42 cartas de poderes.<\/li>\n<li>Un mapa de combate de doble cara.<\/li>\n<li>Seis dados poli\u00e9dricos.<\/li>\n<\/ul>\n<p>Precio: 30 euros la versi\u00f3n espa\u00f1ola, <a href=\"https:\/\/www.bookdepository.com\/es\/Dungeons-Dragons-Fantasy-Roleplaying-Game-Essential-D-D-Starter-James-Wyatt\/9780786956296\" target=\"_blank\" rel=\"noopener noreferrer\">15,43<\/a> la versi\u00f3n en ingl\u00e9s.<\/p>\n<p><strong>Aventuras de la Marca del Este<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22241\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1.jpg\" alt=\"\" width=\"1023\" height=\"793\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1.jpg 1023w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1-300x233.jpg 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1-150x116.jpg 150w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1-768x595.jpg 768w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1-696x540.jpg 696w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/LMDE_1-542x420.jpg 542w\" sizes=\"auto, (max-width: 1023px) 100vw, 1023px\" \/><\/strong><\/p>\n<p style=\"text-align: center;\">\n<p>Por incre\u00edble que parezca, no he encontrado la lista de futuros componentes en un art\u00edculo del propio blog de <a href=\"https:\/\/www.lamarcadeleste.com\/search\/label\/Aventuras%20en%20la%20Marca%20del%20Este\" target=\"_blank\" rel=\"noopener noreferrer\">la Marca del Este<\/a> (aunque tal vez estaba en los comentarios), sino en dos blogs guiris: <a href=\"https:\/\/grognardia.blogspot.com\/2010\/06\/speaking-of-spanish-language-news.html\" target=\"_blank\" rel=\"noopener noreferrer\">Grognardia<\/a> y <a href=\"https:\/\/poleandrope.blogspot.com\/2010\/06\/spanish-language-retro-clone-si.html\" target=\"_blank\" rel=\"noopener noreferrer\">The Society of Torch, Pole and Rope<\/a>:<\/p>\n<p><span style=\"color: #ff6600;\">EDITADO: el mism\u00edsmo <strong>Steinkel<\/strong> ha tenido a bien detallar los componentes de la caja en <a href=\"https:\/\/erekibeon.com\/blog\/dd-essentials-vs-ame\/#comment-1473\" target=\"_blank\" rel=\"noopener noreferrer\">este comentario<\/a> y los pongo aqu\u00ed:<br \/>\n<\/span><\/p>\n<ul>\n<li>Libro de reglas de 150 p\u00e1ginas aproximadamente, en r\u00fastica fresada. Portada a color e interior en blanco y negro. Impresi\u00f3n digital. El sistema es D&amp;D B\u00e1sico revisado, llevando a los personajes de nivel 1 al 20, y contiene reglas, ambientaci\u00f3n en La Marca del Este, Bestiario (la mayor\u00eda con su ilustraci\u00f3n original) y dos aventuras de inicio. Adem\u00e1s, est\u00e1 prologado por Alex de la Iglesia y por el propio Steinkel.<\/li>\n<li>Pantalla del Narrador (DM) en Offset a color de tres cuerpos con las siguientes medidas: 28\u00d721+21+19.<\/li>\n<li>Juego de siete dados (1d20, 1d12, 2d10, 1d8, 1d6, 1d4).<\/li>\n<li>1 l\u00e1piz personalizado con el logo de la Marca (esto es primicia, no lo hab\u00edamos dicho antes).<\/li>\n<\/ul>\n<p>Precio: 29,95 \u20ac<\/p>\n<h3>Opiniones<\/h3>\n<p>Una vez vista la parte \u00abobjetiva\u00bb de ambas cajas, pasemos a la parte subjetiva. Aunque mi punto de partida es el mismo que Bester expresa en su art\u00edculo <a href=\"https:\/\/besterbrainstormer.blogspot.com\/2010\/09\/d-esenciales-un-tren-que-no-es-para-mi.html\" target=\"_blank\" rel=\"noopener noreferrer\">D&amp;D Esenciales: un tren que no es para m\u00ed<\/a>, es bueno ver qu\u00e9 van comentando otros compa\u00f1eros con criterio similar al m\u00edo que ya han tenido un contacto con el producto. As\u00ed me pas\u00f3 con Dragon Age, del que hab\u00eda pasado bastante hasta que al gran Selenio le dio por hacer <a href=\"https:\/\/web.archive.org\/web\/20110608122720\/https:\/\/kelesumocom.ipage.com\/bureaunoir\/?p=187\" target=\"_blank\" rel=\"noopener noreferrer\">esta magn\u00edfica rese\u00f1a<\/a>.<\/p>\n<p>Veamos las mejores rese\u00f1as sobre la Caja de Devir&#8230;<\/p>\n<p>Mario se pill\u00f3 la Caja Roja, pero en ingl\u00e9s y por 13 \u20ac. Aun as\u00ed, por lo que dice en su <a href=\"https:\/\/ethelnir.wordpress.com\/2010\/09\/13\/reportaje-caja-roja-nivel-36\/\" target=\"_blank\" rel=\"noopener noreferrer\">Reportaje: Caja Roja<\/a>, no parece muy contento con la adquisici\u00f3n. Tambi\u00e9n Velasco <a href=\"https:\/\/tranquilosonminions.blogspot.com\/2010\/09\/d-essentials-si-yo-cai-enamorado-de-la.html\" target=\"_blank\" rel=\"noopener noreferrer\">cay\u00f3 enamorado de la moda juvenil<\/a>, y, aunque su impresi\u00f3n es m\u00e1s favorable, su conclusi\u00f3n es la misma que la de Bester: que no es caja para viejos (roleros).<\/p>\n<p>La m\u00e1s completa, desde luego, es la de Alex Werden en el blog de la Fundaci\u00f3n Kaufman: <a href=\"https:\/\/fundacionkaufman.blogspot.com\/2010\/09\/resolviendo-dudas-sobre-la-caja-roja.html\" target=\"_blank\" rel=\"noopener noreferrer\">Resolviendo dudas sobre la Caja Roja<\/a>, donde no s\u00f3lo examina a fondo dicha Caja sino que tambi\u00e9n la compara con lo que se espera de AME. Desde luego, a m\u00ed me ha resuelto casi todas las dudas.<\/p>\n<p>En definitiva, por lo visto lo m\u00e1s productivo que se puede hacer con la Caja Roja es lo que sugieren en Mule Abides (blog cuyo descubrimiento le agradezco sobremanera a <a href=\"https:\/\/elragnablog.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ragna<\/a>): <a href=\"https:\/\/muleabides.wordpress.com\/2010\/09\/17\/lend-a-kid-your-red-box-essentials-starter-set\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lend a kid your red box essentials starter set<\/a>. Aunque no estoy yo para gastarme 30 euros y regalarla a ni\u00f1os en la puerta del cole, es cierto que es un pedazo de labor envangelizadora el que estas cajas empiecen a venderse en centros comerciales y dem\u00e1s. Una buena forma de introducir sangre nueva en este mundillo, aunque sea a trav\u00e9s de una Caja un poco&#8230; insuficiente.<\/p>\n<p>Muy bien, descartada la Caja Roja para mi hueco de la tele. Pero \u00bfy la caja de Aventuras de la Marca del Este? Pues aunque no hemos visto nada f\u00edsico aparte de <a href=\"https:\/\/www.lamarcadeleste.com\/2010\/05\/los-dados-para-nuestro-juego.html\" target=\"_blank\" rel=\"noopener noreferrer\">los dados<\/a> y de <a href=\"https:\/\/www.lamarcadeleste.com\/2010\/08\/prueba-preliminar-de-maquetacion-de.html\" target=\"_blank\" rel=\"noopener noreferrer\">esa prueba de maquetaci\u00f3n<\/a>, prefiero apostar por ella por las siguientes razones:<\/p>\n<ul>\n<li>Porque trae un juego completo en una sola caja.<\/li>\n<\/ul>\n<ul>\n<li>Por la atenci\u00f3n que est\u00e1n prestando a los aficionados de cara a algunas decisiones, como bien se\u00f1ala Crom en su cuarto cromcast. A m\u00ed me ganaron el d\u00eda en que anunciaron que <a href=\"https:\/\/www.lamarcadeleste.com\/2010\/08\/sistema-imperial-o-sistema-metrico.html\" target=\"_blank\" rel=\"noopener noreferrer\">iban a utilizar el sistema m\u00e9trico decimal en lugar del sistema imperial,<\/a> que puede que sea un detallito sin importancia, pero como <a href=\"https:\/\/erekibeon.com\/blog\/gracias-sr-zamarreno\/\" target=\"_blank\" rel=\"noopener noreferrer\">ya le expres\u00e9 <\/a>al <a href=\"https:\/\/zjordi.blogspot.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">sr. Zamarre\u00f1o<\/a> tiempo ha, a m\u00ed me mola. Esto tambi\u00e9n me demostr\u00f3 que hay un mont\u00f3n de compa\u00f1eros roleros que piensan como yo y que est\u00e1n atentos a lo que van anunciando, con lo que estoy seguro de que el producto final se adaptar\u00e1 a mis gustos como si lo hubiera hecho yo mismo.<\/li>\n<li>Porque no han olvidado la frase que aparec\u00eda en la tapa de la Caja inicial:\u00a0 \u00abEste juego no necesita tablero porque la acci\u00f3n transcurre en la mente de los participantes\u00bb.<\/li>\n<\/ul>\n<p>Vale, ya est\u00e1 decidido. Ahora s\u00f3lo queda esperar y rezar a Crom para que haya suerte, porque, por lo que se dice por ah\u00ed, hacerse con una sola caja de la primera tirada va a ser poco menos que una loter\u00eda&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La otra pol\u00e9mica del verano, aunque en esta ocasi\u00f3n creo que ha sido un c\u00famulo de malentendidos. Nunca he sido muy fan de Devir, pero eso de pensar que hayan contraprogramado las Aventuras de la Marca del Este con la Caja Roja&#8230; pufff. Dada su historia de no hacer ni caso al aficionado o a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":22238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[26,15],"tags":[43,51,95,98,113],"class_list":["post-1785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medieval","category-rol","tag-dd","tag-evangelizacion","tag-rol-espanol","tag-rolesfera","tag-vieja-escuela"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":65,"url":"https:\/\/www.erekibeon.com\/blog\/gracias-sr-zamarreno\/","url_meta":{"origin":1785,"position":0},"title":"Gracias, sr. Zamarre\u00f1o","author":"Erek\u00edbeon","date":"09\/07\/2008","format":false,"excerpt":"Estimado Sr. Zamarre\u00f1o: No creo que recuerde cierta conversaci\u00f3n telef\u00f3nica que tuvimos en 2001, cuando su editorial (Devir Ib\u00e9rica S.L.) sac\u00f3 al mercado espa\u00f1ol la \"traducci\u00f3n\" de la tercera edici\u00f3n de Dungeons & Dragons. Estuvimos hablando durante un corto espacio de tiempo sobre los diferentes puntos de vista que usted\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3074,"url":"https:\/\/www.erekibeon.com\/blog\/noticias-que-me-han-interesado\/","url_meta":{"origin":1785,"position":1},"title":"Noticias que me han interesado","author":"Erek\u00edbeon","date":"21\/10\/2011","format":false,"excerpt":"Esta semanita ha sido bastante prol\u00edfica en cuanto a noticias. No rivalizar\u00e1n en relevancia con las noticias hist\u00f3ricas como la muerte de Gadafi o el supuesto \"fin de la lucha armada\" de esa panda de bastardos... pero bueno, son cosillas que han pasado en nuestro mundillo y que me han\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/MM-Compendium.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/MM-Compendium.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/MM-Compendium.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/MM-Compendium.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12334,"url":"https:\/\/www.erekibeon.com\/blog\/6-anos-de-la-partida-de-dave-arneson\/","url_meta":{"origin":1785,"position":2},"title":"6 a\u00f1os de la partida de Dave Arneson","author":"Erek\u00edbeon","date":"08\/04\/2015","format":false,"excerpt":"\u00daltimamente parece esto un blog de necrol\u00f3gicas... pero bueno, a\u00fan guardo la esperanza de que en alg\u00fan momento dejen de encadenarse catarros con virus boca-mano-pie y pueda volver a comentar la actualidad\u00a0rolera m\u00e1s de cerca. Si es que sigue habiendo actualidad rolera cuando todo acabe, claro. :-P Tal d\u00eda como\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/www.erekibeon.com\/blog\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Tiradasgygax_zpsslizf7ly.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Tiradasgygax_zpsslizf7ly.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Tiradasgygax_zpsslizf7ly.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":23821,"url":"https:\/\/www.erekibeon.com\/blog\/dados-de-rol-para-mayores-de-14-anos\/","url_meta":{"origin":1785,"position":3},"title":"Dados de rol para mayores de 14 a\u00f1os","author":"Erek\u00edbeon","date":"12\/01\/2024","format":false,"excerpt":"Efectivamente, soy otro de los que compr\u00f3 el primer n\u00famero del coleccionable de Salvat. Y es que por ese precio no hay que pens\u00e1rselo. \u00bf2 euros por una lata tan pintona, con el logo oficial de D&D y los siete dados can\u00f3nicos encastrados en espuma de embalaje? P\u00f3ngame tres (o\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":796,"url":"https:\/\/www.erekibeon.com\/blog\/mazes-amp-minotaurs\/","url_meta":{"origin":1785,"position":4},"title":"Mazes &#038; Minotaurs: \u00bfA qu\u00e9 esperas para descarg\u00e1rtelo?","author":"Erek\u00edbeon","date":"12\/11\/2009","format":false,"excerpt":"Durante los \u00faltimos meses\u00a0he estado buscando un juego de rol que se pudiera obtener de forma gratuita y con sabor a la Vieja Escuela para mi proyecto de West Marches. Inicialmente estuve contemplando cosas como Labyrinth Lord o Basic Fantasy, retroclones del D&D B\u00e1sico, pero est\u00e1n en ingl\u00e9s, lo cual\u2026","rel":"","context":"En \u00abRese\u00f1as\u00bb","block_context":{"text":"Rese\u00f1as","link":"https:\/\/www.erekibeon.com\/blog\/category\/resenas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Xena-la-princesa-guerrera.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Xena-la-princesa-guerrera.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Xena-la-princesa-guerrera.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Xena-la-princesa-guerrera.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":970,"url":"https:\/\/www.erekibeon.com\/blog\/libreria51\/","url_meta":{"origin":1785,"position":5},"title":"Librer\u00eda51","author":"Erek\u00edbeon","date":"11\/02\/2010","format":false,"excerpt":"Hace unos d\u00edas Kaliber me se\u00f1al\u00f3 esta tienda virtual, cuya URL tiene un nombre de lo m\u00e1s curioso: https:\/\/www.cuentaconmiespada.com\/ Como ver\u00e9is, se trata de una tienda virtual al estilo de la Fundaci\u00f3n Kaufman o Dracotienda, pero en esta ocasi\u00f3n hay dos peculiaridades que la diferencian del resto. Una son los\u2026","rel":"","context":"En \u00abInternet\u00bb","block_context":{"text":"Internet","link":"https:\/\/www.erekibeon.com\/blog\/category\/cosas-de-internet\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/caja-roja.jpg","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/1785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=1785"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/1785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media\/22238"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=1785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=1785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=1785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}