{"id":1273,"date":"2010-06-23T21:09:34","date_gmt":"2010-06-23T20:09:34","guid":{"rendered":"http:\/\/erekibeon.com\/?p=1273"},"modified":"2010-06-23T21:09:34","modified_gmt":"2010-06-23T20:09:34","slug":"la-maldicion-del-loto-negro","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/la-maldicion-del-loto-negro\/","title":{"rendered":"La maldici\u00f3n del loto negro"},"content":{"rendered":"<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" style=\"border: 10px solid white;\" src=\"https:\/\/i0.wp.com\/3.bp.blogspot.com\/_xt8oiEwpFDo\/TBiHQtTSimI\/AAAAAAAACPs\/k5ih5_Aavag\/s400\/La%2Bmaldici%C3%B3n%2Bdel%2Bloto%2Bnegro.jpg?resize=400%2C300&#038;ssl=1\" alt=\"\" width=\"400\" height=\"300\" \/><\/p>\n<p><em>Es como si cada noche nos lanz\u00e1ramos a vivir en otro mundo. Inclusive, dentro de las disciplinas esot\u00e9ricas se considera al sue\u00f1o como \u201cun ensayo de la muerte\u201d ya que no nos damos cuenta cuando llegamos a ese estado, y la frase \u201cel sue\u00f1o eterno\u201d describe con bastante exactitud lo que podr\u00eda esperarnos una vez terminado nuestro ciclo vital.<\/em><\/p>\n<p><em><strong>La Maldici\u00f3n del Loto negro<\/strong>&#8230;&#8230;en\u00a0<strong>Julio&#8230;<\/strong>y en\u00a0<strong>descarga gratu\u00edta en <a href=\"https:\/\/besterbrainstormer.blogspot.com\/\" target=\"_blank\">BRAINSTORMER<\/a><\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es como si cada noche nos lanz\u00e1ramos a vivir en otro mundo. Inclusive, dentro de las disciplinas esot\u00e9ricas se considera al sue\u00f1o como \u201cun ensayo de la muerte\u201d ya que no nos damos cuenta cuando llegamos a ese estado, y la frase \u201cel sue\u00f1o eterno\u201d describe con bastante exactitud lo que podr\u00eda esperarnos una vez [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[43,95,96,104,113],"class_list":["post-1273","post","type-post","status-publish","format-standard","hentry","category-rol","tag-dd","tag-rol-espanol","tag-rol-gratis","tag-taller","tag-vieja-escuela"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":12004,"url":"https:\/\/www.erekibeon.com\/blog\/hack-slash-blog-index\/","url_meta":{"origin":1273,"position":0},"title":"Hack &#038; Slash: Blog Index","author":"Erek\u00edbeon","date":"03\/02\/2014","format":"link","excerpt":"Curios\u00edsimo blog dedicado al arte del mastereo en la Old School Renaissance, que toca pr\u00e1cticamente todos los palos posibles. Sostiene que el m\u00e1ster deber\u00eda darle todo bien mascadito a los jugadores en lugar de dejar que ellos hagan el esfuerzo de entender qu\u00e9 est\u00e1 pasando, pero tambi\u00e9n propone soluciones para\u2026","rel":"","context":"En \u00abMedieval\u00bb","block_context":{"text":"Medieval","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/medieval\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":937,"url":"https:\/\/www.erekibeon.com\/blog\/oferta-solidaria-en-rpgnow-y-drivethrurpg\/","url_meta":{"origin":1273,"position":1},"title":"Oferta solidaria en RPGNow y DrivethruRPG","author":"Erek\u00edbeon","date":"21\/01\/2010","format":false,"excerpt":"V\u00eda GnomeStew (como viene siendo habitual) me he enterado de esta promoci\u00f3n de estas dos tiendas virtuales de PDFs: DrivethruRPG y RPGNow, ambas propiedad de la empresa OneBookShelf.inc. Consiste en un cup\u00f3n de 20$, dinero que ir\u00e1 \u00edntegramente a un fondo de Doctors Without Borders (la matriz de nuestra M\u00e9dicos\u2026","rel":"","context":"En \u00abNoticias\u00bb","block_context":{"text":"Noticias","link":"https:\/\/www.erekibeon.com\/blog\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/PSIMWP1005_500-233x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":970,"url":"https:\/\/www.erekibeon.com\/blog\/libreria51\/","url_meta":{"origin":1273,"position":2},"title":"Librer\u00eda51","author":"Erek\u00edbeon","date":"11\/02\/2010","format":false,"excerpt":"Hace unos d\u00edas Kaliber me se\u00f1al\u00f3 esta tienda virtual, cuya URL tiene un nombre de lo m\u00e1s curioso: https:\/\/www.cuentaconmiespada.com\/ Como ver\u00e9is, se trata de una tienda virtual al estilo de la Fundaci\u00f3n Kaufman o Dracotienda, pero en esta ocasi\u00f3n hay dos peculiaridades que la diferencian del resto. Una son los\u2026","rel":"","context":"En \u00abInternet\u00bb","block_context":{"text":"Internet","link":"https:\/\/www.erekibeon.com\/blog\/category\/cosas-de-internet\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":932,"url":"https:\/\/www.erekibeon.com\/blog\/rol-y-ninos-3\/","url_meta":{"origin":1273,"position":3},"title":"Rol y ni\u00f1os (3)","author":"Erek\u00edbeon","date":"25\/01\/2010","format":false,"excerpt":"Aprovecho que he encontrado m\u00e1s material sobre este tema para guardarme unos cuantos enlaces y compartirlos con vosotros. Mouse Guard Mira que lo tengo en casa y todo, pero a\u00fan no me he sentado propiamente a mirarlo de cerca. Por lo que estoy leyendo en diversos blogs y foros, parece\u2026","rel":"","context":"En \u00abNi\u00f1os\u00bb","block_context":{"text":"Ni\u00f1os","link":"https:\/\/www.erekibeon.com\/blog\/category\/ninos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Skeleton-Pirates-800x600-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Skeleton-Pirates-800x600-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Skeleton-Pirates-800x600-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Skeleton-Pirates-800x600-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":835,"url":"https:\/\/www.erekibeon.com\/blog\/el-laboratorio-de-dexter-d-dd\/","url_meta":{"origin":1273,"position":4},"title":"El laboratorio de Dexter: D &#038; DD","author":"Erek\u00edbeon","date":"28\/11\/2009","format":false,"excerpt":"https:\/\/www.youtube.com\/watch?v=5fkTiopwwCs Hace un mont\u00f3n que vi este cap\u00edtulo en el Cartoon Network, donde Dexter juega al Mazes & Minot... esteeee... Monsters & Mazes \u00a0;-) y me qued\u00e9 con ganas de volver a verlo con m\u00e1s detalle. Demos gracias a Crom por el Youtube, jejeje. Y por si fuera poco friki\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/img.youtube.com\/vi\/5fkTiopwwCs\/0.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":23821,"url":"https:\/\/www.erekibeon.com\/blog\/dados-de-rol-para-mayores-de-14-anos\/","url_meta":{"origin":1273,"position":5},"title":"Dados de rol para mayores de 14 a\u00f1os","author":"Erek\u00edbeon","date":"12\/01\/2024","format":false,"excerpt":"Efectivamente, soy otro de los que compr\u00f3 el primer n\u00famero del coleccionable de Salvat. Y es que por ese precio no hay que pens\u00e1rselo. \u00bf2 euros por una lata tan pintona, con el logo oficial de D&D y los siete dados can\u00f3nicos encastrados en espuma de embalaje? P\u00f3ngame tres (o\u2026","rel":"","context":"En \u00abrol\u00bb","block_context":{"text":"rol","link":"https:\/\/www.erekibeon.com\/blog\/category\/rol\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?fit=1080%2C928&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?fit=1080%2C928&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?fit=1080%2C928&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?fit=1080%2C928&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Revistasdados.webp?fit=1080%2C928&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/1273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=1273"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/1273\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=1273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=1273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=1273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}