{"id":12708,"date":"2015-09-18T09:38:17","date_gmt":"2015-09-18T07:38:17","guid":{"rendered":"http:\/\/www.erekibeon.com\/blog\/?p=12708"},"modified":"2023-01-03T10:57:58","modified_gmt":"2023-01-03T09:57:58","slug":"cambiando-de-casa","status":"publish","type":"post","link":"https:\/\/www.erekibeon.com\/blog\/cambiando-de-casa\/","title":{"rendered":"Cambiando de casa"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Pues\u00a0\u00e9sta es la raz\u00f3n por la que llevo desaparecido desde antes de verano y que me va a mantener con un perfil bajo durante un mes y pico m\u00e1s, por lo menos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Y es que no es tan f\u00e1cil\u00a0como decir \u00abhale, v\u00e1monos a otra casa\u00bb y ya est\u00e1. Ojal\u00e1. Un cambio de domicilio conlleva\u00a0una aut\u00e9ntica\u00a0constelaci\u00f3n\u00a0de decisiones, c\u00e1lculos, tr\u00e1mites y\u00a0detalles que hay que estudiar con la m\u00e1xima atenci\u00f3n, porque van a condicionar nuestra vida de aqu\u00ed en adelante. No s\u00f3lo por los metros cuadrados o la distancia a la que tendremos los colegios, trabajos, hospitales, etc, sino tambi\u00e9n por la pasta que nos quedar\u00e1 cada mes para lujos como comer, vestirse o tener luz. As\u00ed que no queda otra que\u00a0echarle todas las horas posibles\u00a0y pens\u00e1rselo todo muy bien,\u00a0que nos la jugamos\u00a0de verdad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo cierto es que sab\u00edamos que tendr\u00edamos que cambiarnos a otra casa casi desde el mismo momento en que nos confirmaron que\u00a0nuestra Princesa iba a tener un hermano y no una hermana. Lo que no ten\u00edamos claro era si iba a ser m\u00e1s tarde o m\u00e1s temprano. Pero cuando comprobamos lo r\u00e1pido que est\u00e1 creciendo el B\u00e1rbaro\u00a0(que va dejando atr\u00e1s lo de \u00abpeque\u00f1o\u00bb a pasos agigantados) y la tendencia que va tomando el precio\u00a0de la vivienda, decidimos que ahora era el momento. Y a finales de mayo nos pusimos en serio a la tarea.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tengo que confesar que esta entrada iba a ser un tochopost\u00a0lleno de detalles sobre cada\u00a0etapa que vamos atravesando\u00a0(venta de la casa, negociaci\u00f3n de la hipoteca, compra de la casa, reforma, mudanza&#8230; ) pensando en que podr\u00eda serle\u00a0\u00fatil a quien estuviera a punto de hacer lo mismo. Sin embargo, hace unos d\u00edas me dio por leer el borrador con otros ojos y me encontr\u00e9 con una monstruosidad de temas y datos de la \u00abvida real\u00bb que iba a desentonar con el tono general\u00a0del blog cual\u00a0encimera de\u00a0madera sobre suelo porcel\u00e1nico gris. Lo descart\u00e9 y me puse a escribir desde cero, sin m\u00e1s intenci\u00f3n que plasmar lo que me ronda por la cabeza ahora mismo. Y \u00e9ste es el resultado.<br \/>\n<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13363\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2016\/07\/llave.jpg\" alt=\"\" width=\"650\" height=\"595\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2016\/07\/llave.jpg 650w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2016\/07\/llave-300x275.jpg 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2016\/07\/llave-164x150.jpg 164w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2016\/07\/llave-150x137.jpg 150w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p><em><strong>Arriba las llaves antiguas, abajo las nuevas. Ambos son llaveros de los <a href=\"https:\/\/web.archive.org\/web\/20140816152047\/https:\/\/www.clanexploradores.com\/\" target=\"_blank\" rel=\"noopener\">Exploradores de Camelot<\/a>, regalo de un Explorador que se los\u00a0curr\u00f3 all\u00e1 por 2000. Ya veis, chicos, os he tenido\u00a0estos 15 a\u00f1os en mi mente. . . y en mi bolsillo. Y os seguir\u00e9 teniendo en ambos. \ud83d\ude09<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400;\">Y es que, aunque me encanta la perspectiva del cambio y c\u00f3mo est\u00e1 quedando la nueva casa con la reforma, no puedo evitar sentir una punzada de a\u00f1oranza por la que dejamos atr\u00e1s. Cuando la compramos all\u00e1 por 2002 ya ten\u00eda la vaga idea de que no iba a ser la definitiva, pero aun as\u00ed voy a echarla de menos. Ha sido el escenario de tantos principios nuestros\u2026 de nuestra vida de casados, de la vida de nuestros peques y de much\u00edsimos otros proyectos que hemos empezado all\u00ed. Como, sin ir m\u00e1s lejos, este mismo blog que est\u00e1is leyendo ahora.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A mi Reina tambi\u00e9n le pasa lo que a m\u00ed. Sin embargo, para el Peque\u00f1o B\u00e1rbaro la \u00abvieja casa\u00bb no ser\u00e1 m\u00e1s que esos suelos y paredes que salen en sus fotos y v\u00eddeos de beb\u00e9. La que lo ha llevado un poco peor es mi Princesa. Ya est\u00e1 echando de menos su ventana con su \u00e1rbol, al que ha observado c\u00f3mo cambiababa con cada estaci\u00f3n desde que naci\u00f3. Ay, mi pobre Princesa\u2026<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero bueno, esperemos que las vistas de su nueva habitaci\u00f3n le ayuden a ir superando el cambio. Seguro que acabar\u00e1 apreciando que va a vivir en una casa m\u00e1s grande, con una plaza interior y una piscina que har\u00e1 m\u00e1s llevaderos los veranos cada vez m\u00e1s calurosos que har\u00e1n por aqu\u00ed. Y todo ello a 300 metros de donde viv\u00eda antes, yendo a su mismo cole y sin moverse del barrio que les vio nacer, a ellos y a nosotros. Por algo <a href=\"https:\/\/www.erekibeon.com\/blog\/geografia-mitica-del-barrio-del-pilar-castillo-y-villa-de-miralta\" target=\"_blank\" rel=\"noopener\">somos barriodelpilare\u00f1os<\/a> hasta la m\u00e9dula.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como nota curiosa, resulta que la nueva casa est\u00e1 en la misma urbanizaci\u00f3n que ve\u00eda desde la ventana de mi habitaci\u00f3n, en casa de mis padres. Durante 30 a\u00f1os he envidiado c\u00f3mo se lo pasaban los jod\u00edos en la piscina. Pues mira por d\u00f3nde, despu\u00e9s de haber visitado una decena de casas en 5 kms a la redonda, al final he acabado siendo uno de esos jod\u00edos \ud83d\ude00 . Creo que <a href=\"https:\/\/www.erekibeon.com\/blog\/veinte-anos-despues\/\" target=\"_blank\" rel=\"noopener\">mi yo de 12 a\u00f1os va a tener un morat\u00f3n en el costado<\/a> con tanto codazo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Aunque bueno, esto a\u00fan no se ha acabado. Es verdad que lo m\u00e1s intenso lo pasamos en agosto, en este verano sin playa, pero a\u00fan nos queda finalizar las obras (pufff) y la mudanza, que ya llevamos preparando desde hace semanas. Y luego vendr\u00e1 ese per\u00edodo de adaptaci\u00f3n en el que tendremos que realizar peque\u00f1os ajustes imprevistos tipo \u201cuy, nos falta un mueble en este rinc\u00f3n\u201d&#8230; con lo que calculo que para noviembre podremos dar por finalizada la odisea.<\/span><\/p>\n<figure id=\"attachment_23376\" aria-describedby=\"caption-attachment-23376\" style=\"width: 660px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-23376 size-full\" src=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/cajas_zps9avjm1ha.jpg\" alt=\"\" width=\"660\" height=\"371\" srcset=\"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/cajas_zps9avjm1ha.jpg 660w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/cajas_zps9avjm1ha-300x169.jpg 300w, https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/cajas_zps9avjm1ha-150x84.jpg 150w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><figcaption id=\"caption-attachment-23376\" class=\"wp-caption-text\">54 cajas s\u00f3lo de cosas del sal\u00f3n&#8230;<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">As\u00ed que ya veis,\u00a0todav\u00eda tengo entretenimiento para una temporadita. Entre tanto, el frente friki lo tengo bastante en segundo plano, limit\u00e1ndome a apuntar breves notas para desarrollar\u00a0m\u00e1s adelante, a leer por encima\u00a0redes sociales y blogs y a echar alguna partida que otra por la noche, cuando el cerebro ya no da m\u00e1s que para actos reflejos y b\u00e1sicos. No me ha quedado otra\u00a0que mantenerme al margen de actividades y eventos\u00a0de mayor entidad, como las SGRIs o, sin ir m\u00e1s lejos, las Ludo Ergo Sum que se van a celebrar este fin de semana. Ser\u00e1 la primera vez que no vaya en los \u00faltimos cuatro a\u00f1os, y ya estoy echando de menos no poder ver a tanta gente con la\u00a0que tengo tantas ganas de compartir algo de tiempo, yantar y chanzas. M\u00e1s vale que las\u00a0LES 2016 se preparen porque pienso desquitarme.<\/span><\/p>\n<p>En fin, tengo curiosidad por saber qu\u00e9 pasa cuando se acabe todo esto. Yo\u00a0espero que\u00a0tanto cambio\u00a0tambi\u00e9n\u00a0influya de alguna manera\u00a0en\u00a0mis h\u00e1bitos de escritura, y ese rinc\u00f3n que me ha habilitado\u00a0mi Reina\u00a0me motive\u00a0para volver con fuerzas redobladas por aqu\u00ed.\u00a0\u00bfLo conseguir\u00e9? Pues&#8230; por aqu\u00ed mismo se ver\u00e1, supongo \ud83d\ude1b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues\u00a0\u00e9sta es la raz\u00f3n por la que llevo desaparecido desde antes de verano y que me va a mantener con un perfil bajo durante un mes y pico m\u00e1s, por lo menos. Y es que no es tan f\u00e1cil\u00a0como decir \u00abhale, v\u00e1monos a otra casa\u00bb y ya est\u00e1. Ojal\u00e1. Un cambio de domicilio conlleva\u00a0una aut\u00e9ntica\u00a0constelaci\u00f3n\u00a0de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[533,79,532],"class_list":["post-12708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-cotidiana","tag-barrio-del-pilar","tag-ninos-2","tag-vida-real"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":25606,"url":"https:\/\/www.erekibeon.com\/blog\/18-anos\/","url_meta":{"origin":12708,"position":0},"title":"18 a\u00f1os","author":"Erek\u00edbeon","date":"10\/11\/2025","format":false,"excerpt":"Pues s\u00ed. Hace poco que Fusa, tambi\u00e9n conocida por el blog como \"mi Princesa\", cumpli\u00f3 los 18. Y sus padres la seguimos queriendo much\u00edsimo. Mucha gente agregar\u00eda en este punto aquello de \"igual que el primer d\u00eda\". Pero eso no s\u00f3lo habr\u00eda sido una frase hecha (y cursi elevada a\u2026","rel":"","context":"En \u00abNi\u00f1os\u00bb","block_context":{"text":"Ni\u00f1os","link":"https:\/\/www.erekibeon.com\/blog\/category\/ninos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/18anosraster.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/18anosraster.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/18anosraster.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/18anosraster.webp?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/18anosraster.webp?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15075,"url":"https:\/\/www.erekibeon.com\/blog\/1o-de-la-eso-preparados-para-lo-real-no-tanto-para-lo-digital\/","url_meta":{"origin":12708,"position":1},"title":"1\u00ba de la ESO: preparados para lo real, no tanto para lo digital.","author":"Erek\u00edbeon","date":"01\/11\/2019","format":false,"excerpt":"Cu\u00e1ntos cambios trae el instituto. Profesores diferentes y cambios de aula para cada asignatura, mochilas que pasan de los 7 kilos (\"pap\u00e1, ir con trolley es de beb\u00e9s\") y horarios de salida totalmente incompatibles con los de cualquier jornada laboral. Algunos chavales tendr\u00e1n la suerte de contar con alguien que\u2026","rel":"","context":"En \u00abNi\u00f1os\u00bb","block_context":{"text":"Ni\u00f1os","link":"https:\/\/www.erekibeon.com\/blog\/category\/ninos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/ni%C3%B1osmovil.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/ni%C3%B1osmovil.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/ni%C3%B1osmovil.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/ni%C3%B1osmovil.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/ni%C3%B1osmovil.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/ni%C3%B1osmovil.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14081,"url":"https:\/\/www.erekibeon.com\/blog\/estrenando-cabecera\/","url_meta":{"origin":12708,"position":2},"title":"Estrenando cabecera","author":"Erek\u00edbeon","date":"20\/10\/2017","format":false,"excerpt":"Y es que el Peque\u00f1o B\u00e1rbaro ya hace una temporada que no lleva ni pa\u00f1ales ni chupete, as\u00ed que iba siendo hora de darle un retoque a las figurillas que nos representan al lado del t\u00edtulo. Para esta ocasi\u00f3n he tenido el inmenso honor y el placer de contar con\u2026","rel":"","context":"En \u00abFrikismo\u00bb","block_context":{"text":"Frikismo","link":"https:\/\/www.erekibeon.com\/blog\/category\/frikismo\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/2017\/10\/cabeceraazpiri.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":5560,"url":"https:\/\/www.erekibeon.com\/blog\/yo-he-ganado-y-tu-no\/","url_meta":{"origin":12708,"position":3},"title":"Yo he ganado y t\u00fa no","author":"Erek\u00edbeon","date":"04\/09\/2013","format":false,"excerpt":"Hace unos meses, cuando est\u00e1bamos ense\u00f1ando a mi Princesa que ganar o perder por cosas nimias (como la\u00a0carrera de qui\u00e9n entra primero por la puerta de casa) no era tan importante, se nos ocurri\u00f3 una letra para cantar con el estribillo del colosal \"We are the Champions\" de Queen. Y\u2026","rel":"","context":"En \u00abM\u00fasica\u00bb","block_context":{"text":"M\u00fasica","link":"https:\/\/www.erekibeon.com\/blog\/category\/musica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2722,"url":"https:\/\/www.erekibeon.com\/blog\/religion-y-etica\/","url_meta":{"origin":12708,"position":4},"title":"Religi\u00f3n y \u00e9tica","author":"Erek\u00edbeon","date":"11\/02\/2008","format":false,"excerpt":"Como he comentado anteriormente, tengo una Princesa de 4 meses y medio que, como era de esperar, nos ha cambiado la vida a su madre y a m\u00ed en todos los sentidos. Pero tranquilos, que no enumerar\u00e9 la cantidad de cosas que cambian, para eso ya hay otras webs y\u2026","rel":"","context":"En \u00abNi\u00f1os\u00bb","block_context":{"text":"Ni\u00f1os","link":"https:\/\/www.erekibeon.com\/blog\/category\/ninos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":15197,"url":"https:\/\/www.erekibeon.com\/blog\/coronavirus-siguientes-semanas-de-confinamiento\/","url_meta":{"origin":12708,"position":5},"title":"Coronavirus: siguientes semanas de confinamiento","author":"Erek\u00edbeon","date":"26\/04\/2020","format":false,"excerpt":"Es curioso. Cuando miro atr\u00e1s, todos los d\u00edas desde el comienzo de este confinamiento se me funden en una especie de borr\u00f3n. S\u00f3lo al mirar el calendario caigo en la cuenta de cuant\u00edsimos d\u00edas llevamos ya encerrados. Y si esto me pasa ahora \u00bfc\u00f3mo ser\u00e1 dentro de un par de\u2026","rel":"","context":"En \u00abVida cotidiana\u00bb","block_context":{"text":"Vida cotidiana","link":"https:\/\/www.erekibeon.com\/blog\/category\/vida-cotidiana\/"},"img":{"alt_text":"Mascarillas TNT","src":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Mascarillas2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Mascarillas2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Mascarillas2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.erekibeon.com\/blog\/wp-content\/uploads\/Mascarillas2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.erekibeon.com\/blog\/wp-content\/uploads\/2016\/07\/llave.jpg","_links":{"self":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/12708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/comments?post=12708"}],"version-history":[{"count":0,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/posts\/12708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media\/13363"}],"wp:attachment":[{"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/media?parent=12708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/categories?post=12708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erekibeon.com\/blog\/wp-json\/wp\/v2\/tags?post=12708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}